{"id":8192,"date":"2015-10-22T00:00:00","date_gmt":"2015-10-22T00:00:00","guid":{"rendered":"http:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/"},"modified":"2015-10-22T00:00:00","modified_gmt":"2015-10-22T00:00:00","slug":"presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/","title":{"rendered":"Presentes Primavera 2015 se desarroll\u00f3 del 19 al 22 de agosto en La Rural"},"content":{"rendered":"<p>(Buenos Aires, 22 de octubre de 2015). Presentes tuvo en esta oportunidad el lema \u201cTu pr\u00f3xima vidriera\u201d y se extendi\u00f3 durante cuatro jornadas en La Rural. Tuvo m\u00e1s de 23.000 visitantes \u2013entre comerciantes, distribuidores, mayoristas, hoteleros y gastron\u00f3micos de todo el pa\u00eds- y 312 expositores en la 31\u00ba edici\u00f3n de la feria. D\u00e9bora Giorgi, ministra de Industria de la Naci\u00f3n, particip\u00f3 de la inauguraci\u00f3n oficial, adem\u00e1s de los directores de la empresa organizadora, H\u00e9ctor Kandel, Gustavo Koroyan y Daniel Mart\u00ednez Font,<\/p>\n<p>Presentes es una Exposici\u00f3n Internacional de Decoraci\u00f3n, Iluminaci\u00f3n, Muebles, Mesa, Bazar, Cocina, Regalos, Utilitarios, Marroquiner\u00eda, Textil para el Hogar y Navidad. Es exclusivamente de venta mayorista que se encuentra en el mercado hace 15 a\u00f1os. <\/p>\n<p>Particip\u00f3 del corte de cinta D\u00e9bora Giorgi, ministra de Industria de la Naci\u00f3n, adem\u00e1s de los directores de la empresa organizadora, H\u00e9ctor Kandel, Gustavo Koroyan y Daniel Mart\u00ednez Font, quien afirm\u00f3: \u201cPresentes mostr\u00f3 variedad de productos, oportunidades y novedades que fabricantes nacionales e importadores lanzan al mercado\u201d. <\/p>\n<p>Por su parte, Kandel dijo: \u201cNuestro fin es proporcionarles tanto a los expositores como a los visitantes un valor agregado a su actividad comercial para que tengan la ventaja de estar actualizados en los distintos rubros, adquirir nuevos contactos y ampliar su cartera de clientes\u201d. <\/p>\n<p>La feria ocup\u00f3 30.000 metros cuadrados de superficie en diversos rubros, tales como muebles, mesa, decoraci\u00f3n, regalos, Navidad, utilitarios, marroquiner\u00eda, iluminaci\u00f3n,  <br \/>bazar, cocina, textil para el hogar, entre otros. <\/p>\n<p>La 31\u00ba edici\u00f3n de Presentes cont\u00f3 por cuarta vez consecutiva con el espacio del \u201cSello del Buen Dise\u00f1o\u201d, la primera distinci\u00f3n oficial que ofrece el Ministerio de Industria de la Naci\u00f3n a los productos nacionales que se destacan por su dise\u00f1o. <\/p>\n<p>Presentes es una muestra exclusiva para profesionales y est\u00e1 prohibido el ingreso de particulares y de menores de 12. Esta particularidad, adem\u00e1s de que no est\u00e1n autorizadas las ventas ni generar \u00f3rdenes de pedidos, hace que resalte la idea de que en Presentes las empresas exhiben su oferta de productos y se llevan contactos. La mayor\u00eda de los expositores declara que participar de una feria de este tipo les garantiza futuros llamados o correos electr\u00f3nicos para trabajar en los siguientes tres o cuatro meses. <\/p>\n<p>Presentes, al igual que CAFIRA (ver aparte), convocan dos veces al a\u00f1o \u2013a mediados de marzo y a fines de agosto- a compradores de todo el pa\u00eds. Entre ellos, comerciantes, distribuidores, mayoristas, hoteleros y gastron\u00f3mico. <\/p>\n<p>Un sistema de trasbordo gratuito de combis entre Plaza Italia (La Rural) y Costa Salguero les permite a los visitantes recorrer a las dos ferias en el mismo d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Buenos Aires, 22 de octubre de 2015). Presentes tuvo en esta oportunidad el lema \u201cTu pr\u00f3xima vidriera\u201d y se extendi\u00f3 durante cuatro jornadas en La Rural. Tuvo m\u00e1s de 23.000 visitantes \u2013entre comerciantes, distribuidores, mayoristas, hoteleros y gastron\u00f3micos de todo el pa\u00eds- y 312 expositores en la 31\u00ba edici\u00f3n de la feria. D\u00e9bora Giorgi, ministra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-8192","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ferias-y-congresos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentes Primavera 2015 se desarroll\u00f3 del 19 al 22 de agosto en La Rural - D&amp;F Muebles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentes Primavera 2015 se desarroll\u00f3 del 19 al 22 de agosto en La Rural - D&amp;F Muebles\" \/>\n<meta property=\"og:description\" content=\"(Buenos Aires, 22 de octubre de 2015). Presentes tuvo en esta oportunidad el lema \u201cTu pr\u00f3xima vidriera\u201d y se extendi\u00f3 durante cuatro jornadas en La Rural. Tuvo m\u00e1s de 23.000 visitantes \u2013entre comerciantes, distribuidores, mayoristas, hoteleros y gastron\u00f3micos de todo el pa\u00eds- y 312 expositores en la 31\u00ba edici\u00f3n de la feria. D\u00e9bora Giorgi, ministra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/\" \/>\n<meta property=\"og:site_name\" content=\"D&amp;F Muebles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-22T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/10\\\/22\\\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/10\\\/22\\\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\"},\"headline\":\"Presentes Primavera 2015 se desarroll\u00f3 del 19 al 22 de agosto en La Rural\",\"datePublished\":\"2015-10-22T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/10\\\/22\\\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\\\/\"},\"wordCount\":465,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"articleSection\":[\"Ferias y Congresos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/10\\\/22\\\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/10\\\/22\\\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/10\\\/22\\\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\\\/\",\"name\":\"Presentes Primavera 2015 se desarroll\u00f3 del 19 al 22 de agosto en La Rural - D&amp;F Muebles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\"},\"datePublished\":\"2015-10-22T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/10\\\/22\\\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/10\\\/22\\\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/10\\\/22\\\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentes Primavera 2015 se desarroll\u00f3 del 19 al 22 de agosto en La Rural\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"name\":\"D&F Muebles\",\"description\":\"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/author\\\/sachi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentes Primavera 2015 se desarroll\u00f3 del 19 al 22 de agosto en La Rural - D&amp;F Muebles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/","og_locale":"es_ES","og_type":"article","og_title":"Presentes Primavera 2015 se desarroll\u00f3 del 19 al 22 de agosto en La Rural - D&amp;F Muebles","og_description":"(Buenos Aires, 22 de octubre de 2015). Presentes tuvo en esta oportunidad el lema \u201cTu pr\u00f3xima vidriera\u201d y se extendi\u00f3 durante cuatro jornadas en La Rural. Tuvo m\u00e1s de 23.000 visitantes \u2013entre comerciantes, distribuidores, mayoristas, hoteleros y gastron\u00f3micos de todo el pa\u00eds- y 312 expositores en la 31\u00ba edici\u00f3n de la feria. D\u00e9bora Giorgi, ministra [&hellip;]","og_url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/","og_site_name":"D&amp;F Muebles","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2015-10-22T00:00:00+00:00","author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343"},"headline":"Presentes Primavera 2015 se desarroll\u00f3 del 19 al 22 de agosto en La Rural","datePublished":"2015-10-22T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/"},"wordCount":465,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"articleSection":["Ferias y Congresos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/","name":"Presentes Primavera 2015 se desarroll\u00f3 del 19 al 22 de agosto en La Rural - D&amp;F Muebles","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website"},"datePublished":"2015-10-22T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/10\/22\/presentes-primavera-2015-se-desarrollo-del-19-al-22-de-agosto-en-la-rural\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/dyf-muebles\/"},{"@type":"ListItem","position":2,"name":"Presentes Primavera 2015 se desarroll\u00f3 del 19 al 22 de agosto en La Rural"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","name":"D&F Muebles","description":"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera","publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/dyf-muebles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/author\/sachi\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/comments?post=8192"}],"version-history":[{"count":0,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8192\/revisions"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media?parent=8192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/categories?post=8192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/tags?post=8192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}