{"id":8184,"date":"2015-09-03T00:00:00","date_gmt":"2015-09-03T00:00:00","guid":{"rendered":"http:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/"},"modified":"2015-09-03T00:00:00","modified_gmt":"2015-09-03T00:00:00","slug":"sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/","title":{"rendered":"SQL Amoblamientos y los resultados tras tres a\u00f1os de inversi\u00f3n en marketing y publicidad"},"content":{"rendered":"<p>(Buenos Aires, 3 de septiembre de 2015. Por Elisabet Arn).Luego de tres a\u00f1os de inversi\u00f3n en marketing y publicidad, Jorge Urizar -fundador de SQL Amoblamientos, cuya p\u00e1gina web es www.sqlamoblamientos.com.ar- comienza a &quot;ver&quot; los resultados de la inversi\u00f3n. SQL Amoblamientos dise\u00f1a, fabrica y distribuye desde C\u00f3rdoba muebles de cocinas y placares para todo el pa\u00eds. Los invito a descubrir este emprendimiento nacido en 1981 y conocer su desarrollo actual. Galer\u00eda de Im\u00e1genes.<\/p>\n<p>Jorge nos relata algo de sus comienzos: &quot;Logramos sobreponernos a varias crisis. Entre ellas, una muy dura en 2001. Cuando pudimos sobreponernos a esto comenzamos a consolidar el \u00e1rea productiva de la empresa, incorporando maquinaria y tecnolog\u00eda para lograr mayores est\u00e1ndares de calidad. Eso nos permiti\u00f3 comenzar con un plan de expansi\u00f3n comercial a nivel pa\u00eds&quot;. <\/p>\n<p>&#8211; \u00bfC\u00f3mo se fue desarrollando ese plan? <\/p>\n<p>&#8211; Nosotros contamos con un equipo comercial que se encarga de detectar posibles distribuidores. En un principio, sinceramente busc\u00e1bamos abrir nuevos puntos de ventas, motivados por la posibilidad productiva que ten\u00edamos. Con el tiempo adquirimos experiencia y logramos definir un perfil que nos permita una mejor selecci\u00f3n de qui\u00e9nes representen nuestra marca. <\/p>\n<p>&#8211; \u00bfC\u00f3mo es eso? <\/p>\n<p>&#8211; Bueno, nosotros nos iniciamos en este negocio vendiendo muebles de cocinas econ\u00f3micos, muy b\u00e1sicos. Con el tiempo fuimos creciendo en dise\u00f1o y desarrollamos varias l\u00edneas. Actualmente nuestra oferta de productos se orienta a un segmento de mercado medio alto, en el cual el servicio es un tema fundamental. Adem\u00e1s, un amoblamiento de cocina a diferencia del resto necesita una venta m\u00e1s profesionalizada: conocer aspectos t\u00e9cnicos a la hora de tomar medidas, comprender las necesidades del cliente, el estilo que va mejor con la arquitectura de su casa y finalmente proponerle un proyecto. A partir de este mes estamos trabajando en un plan de formaci\u00f3n para nuestros distribuidores, que les permita mejorar sus ventas y, obviamente, las de la empresa. <\/p>\n<p>&#8211; Al inicio me comentabas de un plan de marketing y publicidad, \u00bfpodr\u00edas ampliar informaci\u00f3n sobre esto? <\/p>\n<p>&#8211; S\u00ed. Hace unos a\u00f1os empezamos a trabajar el tema de la marca, que comenz\u00f3 con el redise\u00f1o de nuestro isologotipo; definimos unas im\u00e1genes que nos acompa\u00f1aron un par de a\u00f1os y un eslogan. Tambi\u00e9n trabajamos en &quot;normalizar&quot; nuestra imagen en los locales comerciales. De hecho, a trav\u00e9s de un PACC (NdR: Programa de Acceso al Cr\u00e9dito y la Competitividad de Secretar\u00eda PyME) hicimos manuales con las diferentes tipolog\u00edas arquitect\u00f3nicas y logramos una imagen similar en todos nuestros locales del pa\u00eds. Luego comenzamos a trabajar con una intensa campa\u00f1a publicitaria, principalmente en la provincia de C\u00f3rdoba. En lo que hace a televisi\u00f3n, pero tambi\u00e9n en otros lugares del pa\u00eds, en publicaciones especializadas, carteler\u00eda en ruta, Internet y redes sociales. Todo esto nos ha dado un muy buen resultado. Ahora el desaf\u00edo es seguir creciendo. <\/p>\n<p>&#8211; \u00bfC\u00f3mo han sido las ventas en lo que va de este a\u00f1o? <\/p>\n<p>&#8211; Muy buenas, tanto el nivel de ventas como la captaci\u00f3n de nuevos distribuidores-franquiciados. Hemos abierto una nueva sucursal en la ciudad de Rosario, una plaza que nos interesaba mucho. <\/p>\n<p>&#8211; \u00bfEn que otras localidades han abierto sucursales? <\/p>\n<p>&#8211; Rada Tilly (Chubut), Caleta Olivia (Santa Cruz), San Luis y La Rioja. Tenemos sucursales en pr\u00e1cticamente todo el pa\u00eds, y estamos con muy buen nivel de ventas en el centro del pa\u00eds y el sur. Queremos lograr fortalecernos en el NOA, as\u00ed que estaremos trabajando para lograr m\u00e1s presencia all\u00ed. <\/p>\n<p>&#8211; Antes me comentabas del PACC, que utilizaron para desarrollar la marca. \u00bfQu\u00e9 otras pol\u00edticas de este gobierno les han servido a ustedes? <\/p>\n<p>&#8211; El Ahora 12 moviliz\u00f3 las ventas; el control de las importaciones fue un gran apoyo al sector, dado que como te coment\u00e9 antes en 2001 por las importaciones de productos extranjeros SQL pas\u00f3 por una gran crisis, al igual que muchas de las PyMEs nacionales. <\/p>\n<p>&#8211; En cuanto a los insumos de producci\u00f3n, \u00bfencontr\u00e1s lo que necesitas en el mercado? <\/p>\n<p>&#8211; Si, nuestra empresa no sufri\u00f3 ning\u00fan problema de falta de herrajes o materiales. En algunas cosas tuvimos que acomodarnos, pero todo fue manejable. <\/p>\n<p>&#8211; En cuanto a nuevos dise\u00f1os, \u00bfpiensan desarrollar algo pr\u00f3ximamente? <\/p>\n<p>&#8211; S\u00ed, en octubre pr\u00f3ximo estaremos lanzando una nueva l\u00ednea de productos al mercado, con un concepto muy minimalista. Hace rato estamos trabajando con el equipo de dise\u00f1o, ya en cuestiones t\u00e9cnicas. Esta nueva l\u00ednea estar\u00e1 dentro de nuestro tope de gama. Tenemos muchas expectativa de conocer como la recibir\u00e1 el p\u00fablico. <\/p>\n<p>&#8211; \u00bfQu\u00e9 cosas consider\u00e1s que son la clave del \u00e9xito de tu marca? <\/p>\n<p>&#8211; Bueno, creo que es un conjunto de cosas&#8230; Tenemos una muy buena relaci\u00f3n entre calidad y precio. El p\u00fablico empieza a reconocer la marca, lo que da confiabilidad en la entrega, y tenemos buenas opciones de dise\u00f1o. Actualmente trabajan a la par m\u00edo Nicol\u00e1s y Facundo, mis dos hijos, y Gabriel Caligaris, que si bien no es hijo m\u00edo, lo siento de la familia. Con este equipo nos ocupamos personalmente de dar respuestas r\u00e1pidas a nuestros distribuidores. Vale decir, a pesar del crecimiento seguimos teniendo un trato muy cercano y priorizando la satisfacci\u00f3n del cliente. <\/p>\n<p>&#8211; Jorge, muchas gracias por abrir las puertas de SQL Amoblamientos a D&#038;F Muebles. <\/p>\n<p>* Elisabet Arn (arn.estudio@gmail.com) es dise\u00f1adora e integra el Estudio Arn-Salum. <\/p>\n<p>Fotos: Elisabet Arn y archivo D&#038;F Muebles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Buenos Aires, 3 de septiembre de 2015. Por Elisabet Arn).Luego de tres a\u00f1os de inversi\u00f3n en marketing y publicidad, Jorge Urizar -fundador de SQL Amoblamientos, cuya p\u00e1gina web es www.sqlamoblamientos.com.ar- comienza a &quot;ver&quot; los resultados de la inversi\u00f3n. SQL Amoblamientos dise\u00f1a, fabrica y distribuye desde C\u00f3rdoba muebles de cocinas y placares para todo el pa\u00eds. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3244,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":{"0":"post-8184","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-empresariales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SQL Amoblamientos y los resultados tras tres a\u00f1os de inversi\u00f3n en marketing y publicidad - D&amp;F Muebles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SQL Amoblamientos y los resultados tras tres a\u00f1os de inversi\u00f3n en marketing y publicidad - D&amp;F Muebles\" \/>\n<meta property=\"og:description\" content=\"(Buenos Aires, 3 de septiembre de 2015. Por Elisabet Arn).Luego de tres a\u00f1os de inversi\u00f3n en marketing y publicidad, Jorge Urizar -fundador de SQL Amoblamientos, cuya p\u00e1gina web es www.sqlamoblamientos.com.ar- comienza a &quot;ver&quot; los resultados de la inversi\u00f3n. SQL Amoblamientos dise\u00f1a, fabrica y distribuye desde C\u00f3rdoba muebles de cocinas y placares para todo el pa\u00eds. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/\" \/>\n<meta property=\"og:site_name\" content=\"D&amp;F Muebles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-03T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/01\/04432703092015_Sql2030915.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\"},\"headline\":\"SQL Amoblamientos y los resultados tras tres a\u00f1os de inversi\u00f3n en marketing y publicidad\",\"datePublished\":\"2015-09-03T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/\"},\"wordCount\":976,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/01\\\/04432703092015_Sql2030915.jpg\",\"articleSection\":[\"Empresariales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/\",\"name\":\"SQL Amoblamientos y los resultados tras tres a\u00f1os de inversi\u00f3n en marketing y publicidad - D&amp;F Muebles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/01\\\/04432703092015_Sql2030915.jpg\",\"datePublished\":\"2015-09-03T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/01\\\/04432703092015_Sql2030915.jpg\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/01\\\/04432703092015_Sql2030915.jpg\",\"width\":300,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/09\\\/03\\\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SQL Amoblamientos y los resultados tras tres a\u00f1os de inversi\u00f3n en marketing y publicidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"name\":\"D&F Muebles\",\"description\":\"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/author\\\/sachi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SQL Amoblamientos y los resultados tras tres a\u00f1os de inversi\u00f3n en marketing y publicidad - D&amp;F Muebles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/","og_locale":"es_ES","og_type":"article","og_title":"SQL Amoblamientos y los resultados tras tres a\u00f1os de inversi\u00f3n en marketing y publicidad - D&amp;F Muebles","og_description":"(Buenos Aires, 3 de septiembre de 2015. Por Elisabet Arn).Luego de tres a\u00f1os de inversi\u00f3n en marketing y publicidad, Jorge Urizar -fundador de SQL Amoblamientos, cuya p\u00e1gina web es www.sqlamoblamientos.com.ar- comienza a &quot;ver&quot; los resultados de la inversi\u00f3n. SQL Amoblamientos dise\u00f1a, fabrica y distribuye desde C\u00f3rdoba muebles de cocinas y placares para todo el pa\u00eds. [&hellip;]","og_url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/","og_site_name":"D&amp;F Muebles","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2015-09-03T00:00:00+00:00","og_image":[{"width":300,"height":400,"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/01\/04432703092015_Sql2030915.jpg","type":"image\/jpeg"}],"author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343"},"headline":"SQL Amoblamientos y los resultados tras tres a\u00f1os de inversi\u00f3n en marketing y publicidad","datePublished":"2015-09-03T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/"},"wordCount":976,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/#primaryimage"},"thumbnailUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/01\/04432703092015_Sql2030915.jpg","articleSection":["Empresariales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/","name":"SQL Amoblamientos y los resultados tras tres a\u00f1os de inversi\u00f3n en marketing y publicidad - D&amp;F Muebles","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/#primaryimage"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/#primaryimage"},"thumbnailUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/01\/04432703092015_Sql2030915.jpg","datePublished":"2015-09-03T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/#primaryimage","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/01\/04432703092015_Sql2030915.jpg","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/01\/04432703092015_Sql2030915.jpg","width":300,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/09\/03\/sql-amoblamientos-y-los-resultados-tras-tres-anos-de-inversion-en-marketing-y-publicidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/dyf-muebles\/"},{"@type":"ListItem","position":2,"name":"SQL Amoblamientos y los resultados tras tres a\u00f1os de inversi\u00f3n en marketing y publicidad"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","name":"D&F Muebles","description":"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera","publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/dyf-muebles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/author\/sachi\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/comments?post=8184"}],"version-history":[{"count":0,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media\/3244"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media?parent=8184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/categories?post=8184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/tags?post=8184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}