{"id":8152,"date":"2015-01-26T00:00:00","date_gmt":"2015-01-26T00:00:00","guid":{"rendered":"http:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/"},"modified":"2015-01-26T00:00:00","modified_gmt":"2015-01-26T00:00:00","slug":"ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/","title":{"rendered":"LIGNA 2015 mostrara la fabricaci\u00f3n interconectada para la madera y el mueble"},"content":{"rendered":"<p>(Buenos Aires, 26 de enero de 2015). LIGNA, la mayor feria mundial para la industria forestal que se organiza en Alemania cada dos a\u00f1os, se realizar\u00e1 del 11 al 15 de mayo de 2015. D&#038;F Muebles particip\u00f3 de una rueda promocional que se desarroll\u00f3 en la sede porte\u00f1a de la C\u00e1mara de Industria y Comercio Argentino-Alemana. Uno de los temas centrales de la feria ser\u00e1: \u201cProducci\u00f3n integrada\u201d para el sector de muebles y madera.<\/p>\n<p>Los temas centrales de la pr\u00f3xima edici\u00f3n de la feria ser\u00e1n: \u201cProducci\u00f3n integrada\u201d para el sector de muebles y madera; Procesamiento de pl\u00e1sticos, materiales compuestos y otros componentes; y el estreno de Wood Industry Summit. Jochen K\u00f6ckler, miembro de la junta directiva que organiza la feria, afirm\u00f3: \u201cLa feria de alta tecnolog\u00eda LIGNA 2015 estar\u00e1 dedicada al futuro de la producci\u00f3n. Se expondr\u00e1 cada eslab\u00f3n de la cadena de producci\u00f3n de la industria maderera, centr\u00e1ndose en la creciente convergencia de la producci\u00f3n tradicional con las tecnolog\u00edas de la informaci\u00f3n y de la comunicaci\u00f3n. <\/p>\n<p>La cuarta revoluci\u00f3n industrial ha llegado a la industria maderera y de muebles si partimos de la base de que, en el futuro, las piezas de trabajo, la maquinaria y los sistemas de log\u00edstica se comunicar\u00e1n entre ellos y la tecnolog\u00eda de la informaci\u00f3n, la telecomunicaci\u00f3n y la industria de producci\u00f3n se unir\u00e1n entre s\u00ed\u201d. <\/p>\n<p>En LIGNA se presentan los m\u00e1s destacados desarrollos innovadores y conceptos de soluci\u00f3n para una producci\u00f3n inteligente. La todav\u00eda visi\u00f3n de la &quot;F\u00e1brica Inteligente&quot; en la industria del trabajado y elaboraci\u00f3n de la madera, incluida la industria del mueble, ya est\u00e1 cobrando realidad. La fabricaci\u00f3n de muebles con lotes de tama\u00f1o 1 para clientes individuales exige un alto grado de seguridad de proceso en producci\u00f3n industrial. Disponibilidad de las instalaciones, velocidad de flujo y rendimiento operativo: tres puntos imprescindibles para lograr calidad y eficiencia. Esto exige a su vez, adem\u00e1s de un alto grado de automatizaci\u00f3n, suma precisi\u00f3n en las tecnolog\u00edas m\u00e9tricas. Hay que asegurar la fiabilidad de cada equipo independiente, al igual que la comunicaci\u00f3n de las m\u00e1quinas entre s\u00ed y con el nivel de planificaci\u00f3n y mercado. <\/p>\n<p>Las soluciones de automatizaci\u00f3n inteligentes en la industria de la madera y del mueble pueden lograr que las instalaciones de producci\u00f3n realicen un c\u00e1lculo previo del desgaste de las herramientas, reduzcan las emisiones, optimicen el consumo energ\u00e9tico mediante el control permanente de las necesidades de cada equipo y eviten fallos en la producci\u00f3n. <\/p>\n<p>As\u00ed se minimizan los tiempos de inactividad, los ajustes manuales y las tasas de rechazo, se aumentan el confort de manejo de la maquinaria y la vida \u00fatil de las herramientas, se optimizan los tiempos de flujo, y se potencian tanto la productividad como la eficiencia energ\u00e9tica &#8211; todo ello con los menores costes posibles en concepto de tecnolog\u00edas de automatizaci\u00f3n. <\/p>\n<p>Las tecnolog\u00edas de automatizaci\u00f3n inteligentes contribuyen pues decisivamente a una fabricaci\u00f3n de muebles m\u00e1s flexible, m\u00e1s eficiente y m\u00e1s sostenible. Ya hoy, la tecnolog\u00eda b\u00e1sica de t\u00e9cnicas de control abiertas con apoyo inform\u00e1tico puede ser integrada pr\u00e1ctica y directamente en plantas de producci\u00f3n activas o nuevas. Las modernas tecnolog\u00edas de comunicaci\u00f3n son capaces de integrar en tiempo real los datos de todos los niveles relevantes de planificaci\u00f3n y control. Los proveedores especializados en automatizaci\u00f3n est\u00e1n trabajando ya intensivamente con sus socios en prometedores nuevos conceptos. A tal fin se combinan soluciones de hardware y software mejoradas para realizar potentes soluciones sist\u00e9micas inteligentes que puedan ser enlazadas con las instalaciones de producci\u00f3n con reducido trabajo de programaci\u00f3n. <\/p>\n<p>Christian Pfeiffer, director encargado del departamento LIGNA en Deutsche Messe, Hannover, aclar\u00f3 el objetivo: &quot;El gran desaf\u00edo de cara al futuro consiste en poner a disposici\u00f3n, tambi\u00e9n para las complejas exigencias de la f\u00e1brica inteligente, una arquitectura de control \u00f3ptima. El caso id\u00f3neo incluye tanto la interconexi\u00f3n horizontal de los par\u00e1metros de proceso en cada fase &#8211; desde el pedido, planificaci\u00f3n, producci\u00f3n y log\u00edstica hasta la distribuci\u00f3n &#8211; como a su vez la integraci\u00f3n vertical de los flujos de datos, desde las materias primas hasta el fin de la vida \u00fatil&quot;. <\/p>\n<p>En mayo de 2015 los especialistas internacionales en automatizaci\u00f3n y los constructores de maquinaria del sector presentan sus desarrollos pioneros y aplicaciones piloto exclusivamente en LIGNA. Con una patente demostraci\u00f3n tecnol\u00f3gica de la &quot;fabricaci\u00f3n interconectada&quot; se muestra c\u00f3mo empresas de diferentes magnitudes pueden acceder correctamente a las redes de producci\u00f3n inteligentes. Aqu\u00ed se patentiza: las instalaciones de producci\u00f3n &quot;inteligentes&quot; y capaces de autooptimizarse ofrecen tambi\u00e9n a la industria de la madera y del mueble un enorme potencial de futuro que garantiza calidad, competitividad y flexibilidad. <\/p>\n<p>Fotos: Gentileza Ligna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Buenos Aires, 26 de enero de 2015). LIGNA, la mayor feria mundial para la industria forestal que se organiza en Alemania cada dos a\u00f1os, se realizar\u00e1 del 11 al 15 de mayo de 2015. D&#038;F Muebles particip\u00f3 de una rueda promocional que se desarroll\u00f3 en la sede porte\u00f1a de la C\u00e1mara de Industria y Comercio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-8152","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ferias-y-congresos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LIGNA 2015 mostrara la fabricaci\u00f3n interconectada para la madera y el mueble - D&amp;F Muebles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LIGNA 2015 mostrara la fabricaci\u00f3n interconectada para la madera y el mueble - D&amp;F Muebles\" \/>\n<meta property=\"og:description\" content=\"(Buenos Aires, 26 de enero de 2015). LIGNA, la mayor feria mundial para la industria forestal que se organiza en Alemania cada dos a\u00f1os, se realizar\u00e1 del 11 al 15 de mayo de 2015. D&#038;F Muebles particip\u00f3 de una rueda promocional que se desarroll\u00f3 en la sede porte\u00f1a de la C\u00e1mara de Industria y Comercio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/\" \/>\n<meta property=\"og:site_name\" content=\"D&amp;F Muebles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-26T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/01\\\/26\\\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/01\\\/26\\\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\"},\"headline\":\"LIGNA 2015 mostrara la fabricaci\u00f3n interconectada para la madera y el mueble\",\"datePublished\":\"2015-01-26T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/01\\\/26\\\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\\\/\"},\"wordCount\":866,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"articleSection\":[\"Ferias y Congresos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/01\\\/26\\\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/01\\\/26\\\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/01\\\/26\\\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\\\/\",\"name\":\"LIGNA 2015 mostrara la fabricaci\u00f3n interconectada para la madera y el mueble - D&amp;F Muebles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\"},\"datePublished\":\"2015-01-26T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/01\\\/26\\\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/01\\\/26\\\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2015\\\/01\\\/26\\\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LIGNA 2015 mostrara la fabricaci\u00f3n interconectada para la madera y el mueble\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"name\":\"D&F Muebles\",\"description\":\"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/author\\\/sachi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LIGNA 2015 mostrara la fabricaci\u00f3n interconectada para la madera y el mueble - D&amp;F Muebles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/","og_locale":"es_ES","og_type":"article","og_title":"LIGNA 2015 mostrara la fabricaci\u00f3n interconectada para la madera y el mueble - D&amp;F Muebles","og_description":"(Buenos Aires, 26 de enero de 2015). LIGNA, la mayor feria mundial para la industria forestal que se organiza en Alemania cada dos a\u00f1os, se realizar\u00e1 del 11 al 15 de mayo de 2015. D&#038;F Muebles particip\u00f3 de una rueda promocional que se desarroll\u00f3 en la sede porte\u00f1a de la C\u00e1mara de Industria y Comercio [&hellip;]","og_url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/","og_site_name":"D&amp;F Muebles","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2015-01-26T00:00:00+00:00","author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343"},"headline":"LIGNA 2015 mostrara la fabricaci\u00f3n interconectada para la madera y el mueble","datePublished":"2015-01-26T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/"},"wordCount":866,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"articleSection":["Ferias y Congresos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/","name":"LIGNA 2015 mostrara la fabricaci\u00f3n interconectada para la madera y el mueble - D&amp;F Muebles","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website"},"datePublished":"2015-01-26T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2015\/01\/26\/ligna-2015-mostrara-la-fabricacion-interconectada-para-la-madera-y-el-mueble\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/dyf-muebles\/"},{"@type":"ListItem","position":2,"name":"LIGNA 2015 mostrara la fabricaci\u00f3n interconectada para la madera y el mueble"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","name":"D&F Muebles","description":"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera","publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/dyf-muebles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/author\/sachi\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/comments?post=8152"}],"version-history":[{"count":0,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8152\/revisions"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media?parent=8152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/categories?post=8152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/tags?post=8152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}