{"id":8129,"date":"2014-09-09T00:00:00","date_gmt":"2014-09-09T00:00:00","guid":{"rendered":"http:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/"},"modified":"2014-09-09T00:00:00","modified_gmt":"2014-09-09T00:00:00","slug":"neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/","title":{"rendered":"NEOCON 2014, un encuentro con el dise\u00f1o en Chicago, Estados Unidos"},"content":{"rendered":"<p>(Buenos Aires, 9 de septiembre de 2014. Por Paolo Bergomi, desde Estados Unidos). Chicago, la ciudad del viento, bell\u00edsima y cautivante, plena en verano, complicada en invierno, recibi\u00f3 del 9 al 11 de junio la 46\u00aa edici\u00f3n de la NEOCON, la feria de dise\u00f1o de equipamiento m\u00e1s importante de Estado Unidos. El dise\u00f1ador Paolo Bergomi particip\u00f3 del evento y envi\u00f3 este art\u00edculo especialmente para D&#038;F Muebles.<\/p>\n<p>Con renovado \u00e9xito, esta edici\u00f3n super\u00f3 en un 20% los visitantes de la edici\u00f3n anterior. Cerca de 50.000 profesionales colmaron las instalaciones del tradicional Merchandise Mart, un hervidero de dise\u00f1adores, productores, administradores de empresas, clientes varios y medios de prensa se reunieron para participar de lanzamientos de productos. Y tambi\u00e9n para establecer contactos y estar en la l\u00ednea de partida de las novedades, las ofertas, los intercambios comerciales y educativos. <\/p>\n<p>La innovaci\u00f3n estuvo descollante. El conjunto de la sociedad emprendedora, desde la peque\u00f1a a la gran empresa, desde el proyecto al usuario, reconocen la importancia del dise\u00f1o y as\u00ed lo concretan al verificar el aporte de las soluciones creativas para los ambientes de trabajo, hospitalidad, atenci\u00f3n, salud y educaci\u00f3n. <\/p>\n<p>El dise\u00f1o verde ha sido la figura en escena con la especial estrella de los nuevos materiales. Un sector espec\u00edfico de la muestra estuvo especialmente dedicado a la presentaci\u00f3n de materiales, texturas, colores y acabados. El todo acompa\u00f1ado por seminarios muy ajustados a cada especie, una academia abierta a todos los visitantes con s\u00f3lo sentarse y participar. Una experiencia altamente valiosa y distintiva sobre la manera de organizar las cosas. <\/p>\n<p>La muestra ha respondido en consonancia con el mejoramiento de la situaci\u00f3n econ\u00f3mica en Estados Unidos. La fuerte apuesta de las empresas presentes as\u00ed lo demuestra y la participaci\u00f3n de una importante cantidad de expositores, m\u00e1s de 700, y de visitantes extranjeros, define esta apreciaci\u00f3n. Los stands se presentaron con la austeridad que caracteriza las muestras americanas del sector, en contrapunto quiz\u00e1s con la escenograf\u00eda y grandilocuencia caracter\u00edsticas del Salone del Mobile de Milano, el producto es la figura y la atenci\u00f3n corre por cuenta del propio personal de cada empresa, conocedor de su oferta y responsable de su tarea. <\/p>\n<p>Empresas europeas y de Asia ofrecieron lo mejor de su producci\u00f3n. El visitante pudo disfrutar de productos y firmas destacadas como Poltrona Frau, Cassina, Cappellini, Patricia Urquiola, Steelcase, Natuzzi. Reconocidos profesionales como Todd Bacher, Adrian Smith, Tom Eich brindaron conferencias magistrales a sala llena, en una agenda con seminarios tem\u00e1ticos activamente seguidos por el p\u00fablico. Se alternaron presentaciones en los stands, premiaciones, c\u00f3cteles y actividades m\u00faltiples que bien deber\u00edamos asimilar en nuestras ferias. <\/p>\n<p>Cap\u00edtulo aparte la participaci\u00f3n de las organizaciones de dise\u00f1o y universidades con carreras afines. As\u00ed estuvieron la International Interior Design Association \/ IIDA, la International Association of Lighting Designers \/ IALD, la Interior Design Society IDS, en consonancia con una agenda de actividades especialmente programada para estudiantes de las carreras de dise\u00f1o y arquitectura de 25 universidades de Estados Unidos, con talleres de pr\u00e1cticas de dise\u00f1o y presentaciones de j\u00f3venes valores con un a\u00f1o de egreso de sus centros de estudio. Asimismo, hubo seminarios con costos m\u00ednimos. <\/p>\n<p>Por supuesto que el horario fue nuevamente beneficioso, de 9 de la ma\u00f1ana a 17 horas. O sea, una jornada de trabajo para expositores y visitantes, con el tiempo de encuentros posteriores, tanto sea para la distracci\u00f3n como para el amable avance de acuerdos comerciales. <\/p>\n<p>Otra materia pendiente que nuestros organizadores de exposiciones se niegan a comprender y ponerse en sinton\u00eda con el mundo real. Las exposiciones no deben ser &quot;el paseo de la tarde&quot;, sino el espacio concreto de generar negocios en las horas que los negocios se hacen, productos a mano para testearlos e informaci\u00f3n generosamente disponible en pen drive. Al t\u00e9rmino de la muestra, correos de agradecimiento por la visita y el inter\u00e9s demostrado con respuestas puntuales de precios e informaci\u00f3n t\u00e9cnica. <\/p>\n<p>La edici\u00f3n 2015 se realizar\u00e1 del 15 al 17 de junio. ALADI fue invitada a la feria a trav\u00e9s de su presidente, Paolo Bergomi, juntamente a la Secretaria de Relaciones Internacionales, Beatriz Segni, quienes tomaron contacto con las organizaciones de dise\u00f1o y universidades participantes. <\/p>\n<p>* Paolo I. G. Bergomi es dise\u00f1ador y propietario de Gruppo Bergomi (www.bergomi.com.ar). Es presidente de la Asociaci\u00f3n Latinoamericana de Dise\u00f1o (ALADI). <\/p>\n<p>Fotos: Gentileza Paolo Bergomi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Buenos Aires, 9 de septiembre de 2014. Por Paolo Bergomi, desde Estados Unidos). Chicago, la ciudad del viento, bell\u00edsima y cautivante, plena en verano, complicada en invierno, recibi\u00f3 del 9 al 11 de junio la 46\u00aa edici\u00f3n de la NEOCON, la feria de dise\u00f1o de equipamiento m\u00e1s importante de Estado Unidos. El dise\u00f1ador Paolo Bergomi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-8129","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ferias-y-congresos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NEOCON 2014, un encuentro con el dise\u00f1o en Chicago, Estados Unidos - D&amp;F Muebles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NEOCON 2014, un encuentro con el dise\u00f1o en Chicago, Estados Unidos - D&amp;F Muebles\" \/>\n<meta property=\"og:description\" content=\"(Buenos Aires, 9 de septiembre de 2014. Por Paolo Bergomi, desde Estados Unidos). Chicago, la ciudad del viento, bell\u00edsima y cautivante, plena en verano, complicada en invierno, recibi\u00f3 del 9 al 11 de junio la 46\u00aa edici\u00f3n de la NEOCON, la feria de dise\u00f1o de equipamiento m\u00e1s importante de Estado Unidos. El dise\u00f1ador Paolo Bergomi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/\" \/>\n<meta property=\"og:site_name\" content=\"D&amp;F Muebles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-09T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/09\\\/09\\\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/09\\\/09\\\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\"},\"headline\":\"NEOCON 2014, un encuentro con el dise\u00f1o en Chicago, Estados Unidos\",\"datePublished\":\"2014-09-09T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/09\\\/09\\\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\\\/\"},\"wordCount\":769,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"articleSection\":[\"Ferias y Congresos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/09\\\/09\\\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/09\\\/09\\\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/09\\\/09\\\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\\\/\",\"name\":\"NEOCON 2014, un encuentro con el dise\u00f1o en Chicago, Estados Unidos - D&amp;F Muebles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\"},\"datePublished\":\"2014-09-09T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/09\\\/09\\\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/09\\\/09\\\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/09\\\/09\\\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NEOCON 2014, un encuentro con el dise\u00f1o en Chicago, Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"name\":\"D&F Muebles\",\"description\":\"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/author\\\/sachi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NEOCON 2014, un encuentro con el dise\u00f1o en Chicago, Estados Unidos - D&amp;F Muebles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/","og_locale":"es_ES","og_type":"article","og_title":"NEOCON 2014, un encuentro con el dise\u00f1o en Chicago, Estados Unidos - D&amp;F Muebles","og_description":"(Buenos Aires, 9 de septiembre de 2014. Por Paolo Bergomi, desde Estados Unidos). Chicago, la ciudad del viento, bell\u00edsima y cautivante, plena en verano, complicada en invierno, recibi\u00f3 del 9 al 11 de junio la 46\u00aa edici\u00f3n de la NEOCON, la feria de dise\u00f1o de equipamiento m\u00e1s importante de Estado Unidos. El dise\u00f1ador Paolo Bergomi [&hellip;]","og_url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/","og_site_name":"D&amp;F Muebles","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2014-09-09T00:00:00+00:00","author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343"},"headline":"NEOCON 2014, un encuentro con el dise\u00f1o en Chicago, Estados Unidos","datePublished":"2014-09-09T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/"},"wordCount":769,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"articleSection":["Ferias y Congresos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/","name":"NEOCON 2014, un encuentro con el dise\u00f1o en Chicago, Estados Unidos - D&amp;F Muebles","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website"},"datePublished":"2014-09-09T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/09\/09\/neocon-2014-un-encuentro-con-el-diseno-en-chicago-estados-unidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/dyf-muebles\/"},{"@type":"ListItem","position":2,"name":"NEOCON 2014, un encuentro con el dise\u00f1o en Chicago, Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","name":"D&F Muebles","description":"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera","publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/dyf-muebles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/author\/sachi\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/comments?post=8129"}],"version-history":[{"count":0,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8129\/revisions"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media?parent=8129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/categories?post=8129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/tags?post=8129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}