{"id":8104,"date":"2014-03-27T00:00:00","date_gmt":"2014-03-27T00:00:00","guid":{"rendered":"http:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/"},"modified":"2014-03-27T00:00:00","modified_gmt":"2014-03-27T00:00:00","slug":"presentes-otono-2014-tuvo-record-de-expositores-en-la-rural","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/","title":{"rendered":"Presentes Oto\u00f1o 2014 tuvo r\u00e9cord de expositores en La Rural"},"content":{"rendered":"<p>(Buenos Aires, 27 de marzo de 2014). La feria del sector decoraci\u00f3n, regalos y muebles tuvo en la edici\u00f3n Oto\u00f1o 2014 un total de 308 stands de exhibici\u00f3n y se desarroll\u00f3 del 13 al 16 de marzo en La Rural. En esta oportunidad la organizaci\u00f3n inaugur\u00f3 dos nuevos espacios: Sello del Buen Dise\u00f1o y de los Dise\u00f1adores; y se present\u00f3 la instalaci\u00f3n &quot;La Nube&quot;, de Gaby Boccardo. M\u00e1s informaci\u00f3n: www.presentesonline.com<\/p>\n<p>Presentes, muestra comercial del mercado del regalo, la decoraci\u00f3n y el mueble, cerr\u00f3 su edici\u00f3n Oto\u00f1o reuniendo a un n\u00famero hist\u00f3rico de expositores: 308 stands, que en 30.000 metros cuadrados de superficie permiti\u00f3 desplegar las novedades y \u00faltimas tendencias del sector. <\/p>\n<p>La feria convoc\u00f3 a 25.154 visitantes, se acreditaron 12.061 comercios y se concretaron contactos y operaciones con empresas extranjeras de Brasil, Chile, Paraguay, Uruguay, Bolivia, Estados Unidos y Espa\u00f1a. <\/p>\n<p>Adem\u00e1s, en esta edici\u00f3n se inauguraron dos nuevos espacios: <\/p>\n<p>1- Sello del Buen Dise\u00f1o: a partir de un acuerdo realizado con el Ministerio de Industria de la Naci\u00f3n, en esta \u00e1rea se exhibieron productos nacionales distinguidos con el Sello del Buen Dise\u00f1o en el marco de una importante instalaci\u00f3n en fieltro de lana &quot; La Nube&quot; realizada por la dise\u00f1adora Gaby Boccardo. Algunas de las firmas presentes fueron: Estudio Cabeza, UAU Disegno, Nodo Objetos, Grupo Bondi, Imdi, Nobrand, Corchetes, Designo Patagonia, El Catango, Arqom, entre otras. <\/p>\n<p>2- Espacio de los Dise\u00f1adores: abrazando a &quot;La Nube&quot;  estuvo el sector que reuni\u00f3 a un interesante grupo de j\u00f3venes dise\u00f1adores entre los que figuraron: Chimichurri, Ponte Rey, Ofelia Almac\u00e9n de Dise\u00f1o, Ojo de Pez, La Vie, Voy de Carmen, Frida Cer\u00e1mica, Hilaria Luz, Club de Dise\u00f1o, The little market, Sor Prais, Prouducts, Taller DF Argentina, Iman\u00edas y Fold Design, entre otros. <\/p>\n<p>La pr\u00f3xima edici\u00f3n Presentes Primavera 2014 se realizar\u00e1 en La Rural del 21 al 24 de agosto pr\u00f3ximos. <\/p>\n<p>M\u00e1s informaci\u00f3n: www.presentesonline.com <\/p>\n<p>Fotos: Gentileza Presentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Buenos Aires, 27 de marzo de 2014). La feria del sector decoraci\u00f3n, regalos y muebles tuvo en la edici\u00f3n Oto\u00f1o 2014 un total de 308 stands de exhibici\u00f3n y se desarroll\u00f3 del 13 al 16 de marzo en La Rural. En esta oportunidad la organizaci\u00f3n inaugur\u00f3 dos nuevos espacios: Sello del Buen Dise\u00f1o y de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-8104","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ferias-y-congresos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentes Oto\u00f1o 2014 tuvo r\u00e9cord de expositores en La Rural - D&amp;F Muebles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentes Oto\u00f1o 2014 tuvo r\u00e9cord de expositores en La Rural - D&amp;F Muebles\" \/>\n<meta property=\"og:description\" content=\"(Buenos Aires, 27 de marzo de 2014). La feria del sector decoraci\u00f3n, regalos y muebles tuvo en la edici\u00f3n Oto\u00f1o 2014 un total de 308 stands de exhibici\u00f3n y se desarroll\u00f3 del 13 al 16 de marzo en La Rural. En esta oportunidad la organizaci\u00f3n inaugur\u00f3 dos nuevos espacios: Sello del Buen Dise\u00f1o y de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/\" \/>\n<meta property=\"og:site_name\" content=\"D&amp;F Muebles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-27T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/03\\\/27\\\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/03\\\/27\\\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\"},\"headline\":\"Presentes Oto\u00f1o 2014 tuvo r\u00e9cord de expositores en La Rural\",\"datePublished\":\"2014-03-27T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/03\\\/27\\\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\\\/\"},\"wordCount\":355,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"articleSection\":[\"Ferias y Congresos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/03\\\/27\\\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/03\\\/27\\\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/03\\\/27\\\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\\\/\",\"name\":\"Presentes Oto\u00f1o 2014 tuvo r\u00e9cord de expositores en La Rural - D&amp;F Muebles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\"},\"datePublished\":\"2014-03-27T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/03\\\/27\\\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/03\\\/27\\\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2014\\\/03\\\/27\\\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentes Oto\u00f1o 2014 tuvo r\u00e9cord de expositores en La Rural\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"name\":\"D&F Muebles\",\"description\":\"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/author\\\/sachi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentes Oto\u00f1o 2014 tuvo r\u00e9cord de expositores en La Rural - D&amp;F Muebles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/","og_locale":"es_ES","og_type":"article","og_title":"Presentes Oto\u00f1o 2014 tuvo r\u00e9cord de expositores en La Rural - D&amp;F Muebles","og_description":"(Buenos Aires, 27 de marzo de 2014). La feria del sector decoraci\u00f3n, regalos y muebles tuvo en la edici\u00f3n Oto\u00f1o 2014 un total de 308 stands de exhibici\u00f3n y se desarroll\u00f3 del 13 al 16 de marzo en La Rural. En esta oportunidad la organizaci\u00f3n inaugur\u00f3 dos nuevos espacios: Sello del Buen Dise\u00f1o y de [&hellip;]","og_url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/","og_site_name":"D&amp;F Muebles","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2014-03-27T00:00:00+00:00","author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343"},"headline":"Presentes Oto\u00f1o 2014 tuvo r\u00e9cord de expositores en La Rural","datePublished":"2014-03-27T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/"},"wordCount":355,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"articleSection":["Ferias y Congresos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/","name":"Presentes Oto\u00f1o 2014 tuvo r\u00e9cord de expositores en La Rural - D&amp;F Muebles","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website"},"datePublished":"2014-03-27T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2014\/03\/27\/presentes-otono-2014-tuvo-record-de-expositores-en-la-rural\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/dyf-muebles\/"},{"@type":"ListItem","position":2,"name":"Presentes Oto\u00f1o 2014 tuvo r\u00e9cord de expositores en La Rural"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","name":"D&F Muebles","description":"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera","publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/dyf-muebles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/author\/sachi\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/comments?post=8104"}],"version-history":[{"count":0,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8104\/revisions"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media?parent=8104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/categories?post=8104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/tags?post=8104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}