{"id":8088,"date":"2013-11-28T00:00:00","date_gmt":"2013-11-28T00:00:00","guid":{"rendered":"http:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/"},"modified":"2013-11-28T00:00:00","modified_gmt":"2013-11-28T00:00:00","slug":"expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/","title":{"rendered":"EXPODEMA 2013 avanz\u00f3 en su objetivo de ser una Bienal del Mueble"},"content":{"rendered":"<p>(Buenos Aires, 28 de noviembre de 2013). EXPODEMA 2013 se desarroll\u00f3 del 3 al 6 de octubre en el Predio Ferial de Esperanza. \u201cNos fijamos como objetivo posicionar a la feria como Bienal Internacional del Mueble, que seguramente nos llevar\u00e1 varias ediciones m\u00e1s. Pero entendemos que \u00e9se es el camino a seguir\u201c, dijo en la apertura Carlos Correa, presidente de CIMAE, entidad organizadora. D&#038;F Muebles tuvo un enviado especial a Esperanza.<\/p>\n<p>Un enviado especial de D&#038;F Muebles a Esperanza percibi\u00f3 el repunte de esta muestra que en la primera d\u00e9cada de este siglo lider\u00f3 el segmento de ferias de muebles abiertas a todo p\u00fablico. <\/p>\n<p>Participaron en EXPODEMA 2013 expositores de todas las provincias y es visitada por hombres de negocio y profesionales que llegan desde diversos puntos del pa\u00eds. <\/p>\n<p>Acto de apertura <\/p>\n<p>El acto de apertura oficial se produjo el jueves 3 de octubre desde las 18 en el Predio Feria de Esperanza. <\/p>\n<p>Dijo en la apertura Carlos Correa, presidente de la c\u00e1mara organizadora: <\/p>\n<p>&#8211; \u201cRepasando mis discursos de apertura de los a\u00f1os 1999 y 2001, que fueron a\u00f1os en los cuales me toc\u00f3 la responsabilidad de conducir CIMAE anteriormente, recordaba que en aquella \u00e9poca hacer una feria era como armar una carpa en un hurac\u00e1n -. Eran \u00e9pocas muy dif\u00edciles y, sin embargo, logramos llevar la feria adelante. Y gracias a eso marcamos, quiz\u00e1s, un camino que hoy tiene la feria EXPODEMA y que pudo transformarse en sus quince ediciones anteriores, y seguramente en esta decimosexta lo vamos a consolidar, en una de las ferias m\u00e1s importantes del mueble a nivel nacional; <\/p>\n<p>&#8211; \u201cNo hay dudas de que, cuando en febrero tomamos la conducci\u00f3n de la C\u00e1mara con una nueva Comisi\u00f3n nos imaginamos que ten\u00edamos un trabajo muy arduo por delante, pero nunca semejante desaf\u00edo de poder llevar adelante en siete meses la organizaci\u00f3n de una feria. Mucha gente dio valiosas horas de su esfuerzo y por eso mi especial <br \/>agradecimiento a ellos; <\/p>\n<p>&#8211; \u201cNos fijamos como objetivo posicionar a la feria como Bienal Internacional del Mueble, que seguramente nos llevar\u00e1 varias ediciones m\u00e1s. Pero entendemos que \u00e9se es el camino a seguir. Tenemos mucho camino por realizar, pero tenemos la gran oportunidad de lograrlo. En lo personal, que tengo la posibilidad de asistir a ferias nacionales e internacionales del mueble, les puedo asegurar que EXPODEMA no tiene nada que envidiarle a otras ferias nacionales o internacionales de mueble. Se va a poder disfrutar dise\u00f1o, tanto de productos como de stands; <\/p>\n<p>&#8211; \u201cSe esmeraron todos los expositores, que realmente hoy son los verdaderos protagonistas. Algunas empresas invirtieron varias decenas de miles de pesos y eso l\u00f3gicamente se refleja en una mejor presentaci\u00f3n del producto final y del stand en particular; <\/p>\n<p>&#8211; \u201cAdem\u00e1s, es inevitable hacer un especial agradecimiento a todos los que nos marcaron la buena senda. A mi suegro, Gerardo Mehring, que ya no est\u00e1 y que fundara la C\u00e1mara en 1976. Junto con un grupo de visionarios entendi\u00f3 que la mejor forma de que el sector avanzara es con el trabajo en conjunto, dejando de lado cualquier tipo de ego\u00edsmos e intereses personales. Seguramente, los resultados que uno pretende en la actividad gremial empresaria no siempre se obtienen de la manera ideal. Se hacen denodados esfuerzos, desinteresados, luchando por el bien del sector maderero y por el desarrollo de la comunidad, trabajando en una entidad d\u00e9bil \u2013entre comillas- por sus recursos, que son bajos. Pero, a pesar de todo, estamos convencidos de que \u00e9ste es el camino. Y entonces podemos entender que el objetivo est\u00e1 cumplido; <\/p>\n<p>&#8211; Quiero agradecer a mi familia, mi madre y mi padre, que ya no est\u00e1, porque me marcaron el camino del sacrificio y del trabajo duro. Y un especial agradecimiento a mi esposa y a mis cuatro hijos por mis tantas ausencias. A todo el personal que trabaj\u00f3 en EXPODEMA 2013 y a todos los expositores que, repito, son los verdaderos protagonistas de este evento. Por eso les deseo el mayor de los \u00e9xitos. Muchas gracias tambi\u00e9n al gobierno de Santa Fe y a la municipalidad de Esperanza, la Ministerio de Industria de la Naci\u00f3n, a FAIMA, y al CICAE que es como una entidad madre nuestra. Muchas gracias\u201d. <\/p>\n<p>Fotos: D&#038;F Muebles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Buenos Aires, 28 de noviembre de 2013). EXPODEMA 2013 se desarroll\u00f3 del 3 al 6 de octubre en el Predio Ferial de Esperanza. \u201cNos fijamos como objetivo posicionar a la feria como Bienal Internacional del Mueble, que seguramente nos llevar\u00e1 varias ediciones m\u00e1s. Pero entendemos que \u00e9se es el camino a seguir\u201c, dijo en la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-8088","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ferias-y-congresos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EXPODEMA 2013 avanz\u00f3 en su objetivo de ser una Bienal del Mueble - D&amp;F Muebles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXPODEMA 2013 avanz\u00f3 en su objetivo de ser una Bienal del Mueble - D&amp;F Muebles\" \/>\n<meta property=\"og:description\" content=\"(Buenos Aires, 28 de noviembre de 2013). EXPODEMA 2013 se desarroll\u00f3 del 3 al 6 de octubre en el Predio Ferial de Esperanza. \u201cNos fijamos como objetivo posicionar a la feria como Bienal Internacional del Mueble, que seguramente nos llevar\u00e1 varias ediciones m\u00e1s. Pero entendemos que \u00e9se es el camino a seguir\u201c, dijo en la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/\" \/>\n<meta property=\"og:site_name\" content=\"D&amp;F Muebles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-28T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/11\\\/28\\\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/11\\\/28\\\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\"},\"headline\":\"EXPODEMA 2013 avanz\u00f3 en su objetivo de ser una Bienal del Mueble\",\"datePublished\":\"2013-11-28T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/11\\\/28\\\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\\\/\"},\"wordCount\":730,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"articleSection\":[\"Ferias y Congresos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/11\\\/28\\\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/11\\\/28\\\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/11\\\/28\\\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\\\/\",\"name\":\"EXPODEMA 2013 avanz\u00f3 en su objetivo de ser una Bienal del Mueble - D&amp;F Muebles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\"},\"datePublished\":\"2013-11-28T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/11\\\/28\\\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/11\\\/28\\\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/11\\\/28\\\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EXPODEMA 2013 avanz\u00f3 en su objetivo de ser una Bienal del Mueble\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"name\":\"D&F Muebles\",\"description\":\"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/author\\\/sachi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EXPODEMA 2013 avanz\u00f3 en su objetivo de ser una Bienal del Mueble - D&amp;F Muebles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/","og_locale":"es_ES","og_type":"article","og_title":"EXPODEMA 2013 avanz\u00f3 en su objetivo de ser una Bienal del Mueble - D&amp;F Muebles","og_description":"(Buenos Aires, 28 de noviembre de 2013). EXPODEMA 2013 se desarroll\u00f3 del 3 al 6 de octubre en el Predio Ferial de Esperanza. \u201cNos fijamos como objetivo posicionar a la feria como Bienal Internacional del Mueble, que seguramente nos llevar\u00e1 varias ediciones m\u00e1s. Pero entendemos que \u00e9se es el camino a seguir\u201c, dijo en la [&hellip;]","og_url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/","og_site_name":"D&amp;F Muebles","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2013-11-28T00:00:00+00:00","author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343"},"headline":"EXPODEMA 2013 avanz\u00f3 en su objetivo de ser una Bienal del Mueble","datePublished":"2013-11-28T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/"},"wordCount":730,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"articleSection":["Ferias y Congresos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/","name":"EXPODEMA 2013 avanz\u00f3 en su objetivo de ser una Bienal del Mueble - D&amp;F Muebles","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website"},"datePublished":"2013-11-28T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/11\/28\/expodema-2013-avanzo-en-su-objetivo-de-ser-una-bienal-del-mueble\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/dyf-muebles\/"},{"@type":"ListItem","position":2,"name":"EXPODEMA 2013 avanz\u00f3 en su objetivo de ser una Bienal del Mueble"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","name":"D&F Muebles","description":"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera","publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/dyf-muebles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/author\/sachi\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/comments?post=8088"}],"version-history":[{"count":0,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8088\/revisions"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media?parent=8088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/categories?post=8088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/tags?post=8088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}