{"id":8072,"date":"2013-06-13T00:00:00","date_gmt":"2013-06-13T00:00:00","guid":{"rendered":"http:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/"},"modified":"2013-06-13T00:00:00","modified_gmt":"2013-06-13T00:00:00","slug":"afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/","title":{"rendered":"AFIP dar\u00e1 facilidades de pago de impuestos a PyMEs desde agosto"},"content":{"rendered":"<p>(Buenos Aires, 13 de junio de 2013). La Administraci\u00f3n Federal de Ingreso P\u00fablicos (AFIP) anunci\u00f3 este martes que desde el 1 de agosto habr\u00e1 \u201cMiniplanes\u201d de hasta seis cuotas \u2013con tasas de inter\u00e9s que oscilar\u00e1n entre el 1,35 por ciento y el 3 por ciento- para que las PyMEs puedan saldar deudas fiscales, asegur\u00f3 el administrador de la entidad, Ricardo Echegaray. Fue tras almorzar con la nueva c\u00fapula de la UIA, precis\u00f3 Infobae.com<\/p>\n<p>La medida abarcar\u00e1 al pago de impuestos como IVA, Ganancias, Ingresos Brutos y aportes previsionales, y hab\u00eda sido un reclamo que le hab\u00eda acercado FAIMA a Echegaray el 30 de abril a trav\u00e9s de una carta. El Plan de Pago \u201dMis Facilidades\u201d, que contempla flexibilidad para PyMEs en el pago de aportes impositivos y previsionales, se hab\u00eda dejado de aplicar en febrero. <\/p>\n<p>Echegaray puntualiz\u00f3 que la convocatoria estar\u00e1 destinada a las PyME que &quot;facturen hasta $20 millones al a\u00f1o&quot; y que mantengan deudas tributarias, inform\u00f3 Infobae.com <\/p>\n<p>En la sede de la central fabril y tras almorzar con la nueva c\u00fapula de la UIA que ahora encabeza H\u00e9ctor M\u00e9ndez, el administrador del organismo recaudador efectu\u00f3 este anuncio en respuesta a los reclamos de los empresarios. <\/p>\n<p>La dirigencia empresaria ven\u00eda reclamando la reimplementaci\u00f3n de la resoluci\u00f3n general 2774, conocida como Miniplanes de Pago que permit\u00eda cubrir las deudas en seis meses. <\/p>\n<p>Al respecto, Echegaray consider\u00f3 que &quot;la decisi\u00f3n siempre estuvo, estamos estudiando las cuestiones t\u00e9cnicas&quot; y adelant\u00f3 que las tasas de inter\u00e9s var\u00edan entre 1,35 y 3 por ciento. El r\u00e9gimen abarcar\u00e1 el pago de impuestos como: IVA, Ganancias, Ingresos Brutos, Aportes previsionales, entre otros e incluir\u00e1 un scoring, un sistema de calificaci\u00f3n para que accedan m\u00e1s r\u00e1pidamente y con mejores condiciones aquellos contribuyentes con mejor cumplimiento tributario. <\/p>\n<p>Radiograf\u00eda de la industria <\/p>\n<p>Durante el encuentro en la sede de la central fabril, el flamante presidente de la entidad le dijo al titular de la AFIP que est\u00e1n delineando un \u00edndice Industrial que buscar\u00e1 reflejar la variaci\u00f3n de los costos que tienen los diferentes sector industriales. <\/p>\n<p>De esta manera, todos los meses se difundir\u00e1 las subas que experimentar\u00e1n los costos industriales. <\/p>\n<p>Al respecto, el secretario de la UIA y ex presidente, Jos\u00e9 Ignacio de Mendiguren, explic\u00f3 que &quot;se nos suele acusar que tenemos excesivos m\u00e1rgenes de ganancias. Por esta raz\u00f3n con este \u00edndice quedar\u00e1 al desnudo c\u00f3mo se componen los costos y los m\u00e1rgenes&quot; de rentabilidad. <\/p>\n<p>Pedro Reyna, presidente de FAIMA, hab\u00eda afirmado en la carta que dirigi\u00f3 a Echegaray el 30 de abril: \u201cLas empresas que componen el sector maderero son mayoritariamente PyMEs y en estos momentos atraviesan inconvenientes econ\u00f3micos, dentro de los cuales los que mayor peso tienen son los impositivos y previsionales\u201d. <\/p>\n<p>Y hab\u00eda agregado: \u201cEs sabido que la AFIP tiene rigurosos y acelerados pasos para accionar contra contribuyentes que adeuden alguna obligaci\u00f3n impositiva o previsional. Este proceder, en algunos casos, deriva en el embargo de la cuenta corriente de los empresarios, quedando paralizada una herramienta fundamental de trabajo, afectando su imagen y operatoria con la entidad bancaria\u201d. <\/p>\n<p>Fuente y foto: Infobae.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Buenos Aires, 13 de junio de 2013). La Administraci\u00f3n Federal de Ingreso P\u00fablicos (AFIP) anunci\u00f3 este martes que desde el 1 de agosto habr\u00e1 \u201cMiniplanes\u201d de hasta seis cuotas \u2013con tasas de inter\u00e9s que oscilar\u00e1n entre el 1,35 por ciento y el 3 por ciento- para que las PyMEs puedan saldar deudas fiscales, asegur\u00f3 el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-8072","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-noticias"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AFIP dar\u00e1 facilidades de pago de impuestos a PyMEs desde agosto - D&amp;F Muebles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AFIP dar\u00e1 facilidades de pago de impuestos a PyMEs desde agosto - D&amp;F Muebles\" \/>\n<meta property=\"og:description\" content=\"(Buenos Aires, 13 de junio de 2013). La Administraci\u00f3n Federal de Ingreso P\u00fablicos (AFIP) anunci\u00f3 este martes que desde el 1 de agosto habr\u00e1 \u201cMiniplanes\u201d de hasta seis cuotas \u2013con tasas de inter\u00e9s que oscilar\u00e1n entre el 1,35 por ciento y el 3 por ciento- para que las PyMEs puedan saldar deudas fiscales, asegur\u00f3 el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/\" \/>\n<meta property=\"og:site_name\" content=\"D&amp;F Muebles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-13T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/06\\\/13\\\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/06\\\/13\\\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\"},\"headline\":\"AFIP dar\u00e1 facilidades de pago de impuestos a PyMEs desde agosto\",\"datePublished\":\"2013-06-13T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/06\\\/13\\\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\\\/\"},\"wordCount\":551,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/06\\\/13\\\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/06\\\/13\\\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/06\\\/13\\\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\\\/\",\"name\":\"AFIP dar\u00e1 facilidades de pago de impuestos a PyMEs desde agosto - D&amp;F Muebles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\"},\"datePublished\":\"2013-06-13T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/06\\\/13\\\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/06\\\/13\\\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2013\\\/06\\\/13\\\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AFIP dar\u00e1 facilidades de pago de impuestos a PyMEs desde agosto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"name\":\"D&F Muebles\",\"description\":\"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/author\\\/sachi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AFIP dar\u00e1 facilidades de pago de impuestos a PyMEs desde agosto - D&amp;F Muebles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/","og_locale":"es_ES","og_type":"article","og_title":"AFIP dar\u00e1 facilidades de pago de impuestos a PyMEs desde agosto - D&amp;F Muebles","og_description":"(Buenos Aires, 13 de junio de 2013). La Administraci\u00f3n Federal de Ingreso P\u00fablicos (AFIP) anunci\u00f3 este martes que desde el 1 de agosto habr\u00e1 \u201cMiniplanes\u201d de hasta seis cuotas \u2013con tasas de inter\u00e9s que oscilar\u00e1n entre el 1,35 por ciento y el 3 por ciento- para que las PyMEs puedan saldar deudas fiscales, asegur\u00f3 el [&hellip;]","og_url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/","og_site_name":"D&amp;F Muebles","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2013-06-13T00:00:00+00:00","author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343"},"headline":"AFIP dar\u00e1 facilidades de pago de impuestos a PyMEs desde agosto","datePublished":"2013-06-13T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/"},"wordCount":551,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/","name":"AFIP dar\u00e1 facilidades de pago de impuestos a PyMEs desde agosto - D&amp;F Muebles","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website"},"datePublished":"2013-06-13T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2013\/06\/13\/afip-dara-facilidades-de-pago-de-impuestos-a-pymes-desde-agosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/dyf-muebles\/"},{"@type":"ListItem","position":2,"name":"AFIP dar\u00e1 facilidades de pago de impuestos a PyMEs desde agosto"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","name":"D&F Muebles","description":"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera","publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/dyf-muebles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/author\/sachi\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/comments?post=8072"}],"version-history":[{"count":0,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/8072\/revisions"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media?parent=8072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/categories?post=8072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/tags?post=8072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}