{"id":17109,"date":"2026-07-14T18:38:29","date_gmt":"2026-07-14T21:38:29","guid":{"rendered":"https:\/\/maderamen.com.ar\/dyf-muebles\/?p=17109"},"modified":"2026-07-14T18:38:29","modified_gmt":"2026-07-14T21:38:29","slug":"paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/","title":{"rendered":"Paolo Bergomi fue distinguido por la Universidad de Palermo"},"content":{"rendered":"\n<p><strong>Paolo Bergomi, presidente de ALADI, fue distinguido ayer por la Universidad de Palermo y el Foro de Escuelas de Dise\u00f1o como \u201cInvitado de Honor\u201d de la XXI Semana Internacional del Dise\u00f1o, edici\u00f3n 2026. D&amp;F Muebles tuvo un enviado especial.<\/strong><\/p>\n\n\n\n<p>Universidad de Palermo y el Foro de Escuelas de Dise\u00f1o distinguieron ayer a Paolo Bergomi, presidente de la Asociaci\u00f3n Latinoamericana de Dise\u00f1o (ALADI), como \u201cInvitado de Honor\u201d en la XXI Semana Internacional del Dise\u00f1o edici\u00f3n 2026.<\/p>\n\n\n\n<p>El evento se desarroll\u00f3 en la sede de la casa de estudios ubicada en Cabrera 3641, en el barrio porte\u00f1o de Palermo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">C\u00f3ctel<\/h2>\n\n\n\n<p>D&amp;F Muebles particip\u00f3 ayer del c\u00f3ctel de inauguraci\u00f3n de la XXI Semana Internacional del Dise\u00f1o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"622\" src=\"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo3-14-07-26-1024x622.jpg\" alt=\"Paolo Bergomi fue distinguido\" class=\"wp-image-17112\" srcset=\"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo3-14-07-26-1024x622.jpg 1024w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo3-14-07-26-300x182.jpg 300w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo3-14-07-26-768x466.jpg 768w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo3-14-07-26-692x420.jpg 692w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo3-14-07-26-696x423.jpg 696w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo3-14-07-26-1068x648.jpg 1068w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo3-14-07-26.jpg 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Ante unos 100 asistentes, Bergomi recibi\u00f3 una plaqueta y dijo brevemente:<\/p>\n\n\n\n<p>&#8211; \u201cBuenas tardes a todos. Gracias a la Universidad de Palermo y a todo su equipo;<\/p>\n\n\n\n<p>&#8211; \u201cHace 20 a\u00f1os la Universidad de Palermo nos dio la ocasi\u00f3n de exhibir nuestra muestra \u00b4Hecho en Argentina\u00b4;<\/p>\n\n\n\n<p>&#8211; \u201cDesde ese momento estamos juntos con nuestra gente, con nuestro equipo, nuestro universo ALADI, nuestros queridos colegas latinoamericanos y con muchos amigos;<\/p>\n\n\n\n<p>&#8211; \u201cY eso es lo importante. Ese esp\u00edritu de comunidad es importante cultivarlo porque eso es la ra\u00edz de la victoria;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"633\" src=\"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo2-14-07-26-1024x633.jpg\" alt=\"Paolo Bergomi fue distinguido\" class=\"wp-image-17111\" srcset=\"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo2-14-07-26-1024x633.jpg 1024w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo2-14-07-26-300x185.jpg 300w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo2-14-07-26-768x475.jpg 768w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo2-14-07-26-680x420.jpg 680w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo2-14-07-26-696x430.jpg 696w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo2-14-07-26-1068x660.jpg 1068w, https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo2-14-07-26.jpg 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>&#8211; \u201cAgradezco a los amigos, agradezco a mi familia que me ha acompa\u00f1ado -Beatriz, Adri\u00e1n, Marco-, fundamentalmente al equipo ALADI y como har\u00eda Messi, hago as\u00ed (se\u00f1ala el cielo con ambos dedos \u00edndices), y agradezco a mis padres\u201d.<\/p>\n\n\n\n<p>Fotos: D&amp;F Muebles (Enviado Especial a Universidad de Palermo).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paolo Bergomi, presidente de ALADI, fue distinguido ayer por la Universidad de Palermo y el Foro de Escuelas de Dise\u00f1o como \u201cInvitado de Honor\u201d de la XXI Semana Internacional del Dise\u00f1o, edici\u00f3n 2026. D&amp;F Muebles tuvo un enviado especial. Universidad de Palermo y el Foro de Escuelas de Dise\u00f1o distinguieron ayer a Paolo Bergomi, presidente [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":17110,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,23],"tags":[],"class_list":{"0":"post-17109","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-diseno-y-fabricacion","8":"category-featured"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paolo Bergomi fue distinguido por la Universidad de Palermo<\/title>\n<meta name=\"description\" content=\"Paolo Bergomi, presidente de ALADI, fue distinguido ayer por la Universidad de Palermo y el Foro de Escuelas de Dise\u00f1o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paolo Bergomi fue distinguido por la Universidad de Palermo\" \/>\n<meta property=\"og:description\" content=\"Paolo Bergomi, presidente de ALADI, fue distinguido ayer por la Universidad de Palermo y el Foro de Escuelas de Dise\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/\" \/>\n<meta property=\"og:site_name\" content=\"D&amp;F Muebles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T21:38:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo1-14-07-26.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/c05f216a5663a04adfc7d62d87295459\"},\"headline\":\"Paolo Bergomi fue distinguido por la Universidad de Palermo\",\"datePublished\":\"2026-07-14T21:38:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/\"},\"wordCount\":281,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/bergomipalermo1-14-07-26.jpg\",\"articleSection\":[\"Dise\u00f1o\",\"Principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/\",\"name\":\"Paolo Bergomi fue distinguido por la Universidad de Palermo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/bergomipalermo1-14-07-26.jpg\",\"datePublished\":\"2026-07-14T21:38:29+00:00\",\"description\":\"Paolo Bergomi, presidente de ALADI, fue distinguido ayer por la Universidad de Palermo y el Foro de Escuelas de Dise\u00f1o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/bergomipalermo1-14-07-26.jpg\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/bergomipalermo1-14-07-26.jpg\",\"width\":1400,\"height\":700,\"caption\":\"Paolo Bergomi fue distinguido\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2026\\\/07\\\/14\\\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paolo Bergomi fue distinguido por la Universidad de Palermo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"name\":\"D&F Muebles\",\"description\":\"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/c05f216a5663a04adfc7d62d87295459\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/author\\\/maderamenadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paolo Bergomi fue distinguido por la Universidad de Palermo","description":"Paolo Bergomi, presidente de ALADI, fue distinguido ayer por la Universidad de Palermo y el Foro de Escuelas de Dise\u00f1o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/","og_locale":"es_ES","og_type":"article","og_title":"Paolo Bergomi fue distinguido por la Universidad de Palermo","og_description":"Paolo Bergomi, presidente de ALADI, fue distinguido ayer por la Universidad de Palermo y el Foro de Escuelas de Dise\u00f1o.","og_url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/","og_site_name":"D&amp;F Muebles","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2026-07-14T21:38:29+00:00","og_image":[{"width":1400,"height":700,"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo1-14-07-26.jpg","type":"image\/jpeg"}],"author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/c05f216a5663a04adfc7d62d87295459"},"headline":"Paolo Bergomi fue distinguido por la Universidad de Palermo","datePublished":"2026-07-14T21:38:29+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/"},"wordCount":281,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/#primaryimage"},"thumbnailUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo1-14-07-26.jpg","articleSection":["Dise\u00f1o","Principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/","name":"Paolo Bergomi fue distinguido por la Universidad de Palermo","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/#primaryimage"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/#primaryimage"},"thumbnailUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo1-14-07-26.jpg","datePublished":"2026-07-14T21:38:29+00:00","description":"Paolo Bergomi, presidente de ALADI, fue distinguido ayer por la Universidad de Palermo y el Foro de Escuelas de Dise\u00f1o.","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/#primaryimage","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo1-14-07-26.jpg","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2026\/07\/bergomipalermo1-14-07-26.jpg","width":1400,"height":700,"caption":"Paolo Bergomi fue distinguido"},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2026\/07\/14\/paolo-bergomi-fue-distinguido-por-la-universidad-de-palermo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/dyf-muebles\/"},{"@type":"ListItem","position":2,"name":"Paolo Bergomi fue distinguido por la Universidad de Palermo"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","name":"D&F Muebles","description":"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera","publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/dyf-muebles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/c05f216a5663a04adfc7d62d87295459","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/author\/maderamenadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/17109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/comments?post=17109"}],"version-history":[{"count":1,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/17109\/revisions"}],"predecessor-version":[{"id":17113,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/17109\/revisions\/17113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media\/17110"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media?parent=17109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/categories?post=17109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/tags?post=17109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}