{"id":12208,"date":"2019-12-13T11:20:20","date_gmt":"2019-12-13T14:20:20","guid":{"rendered":"https:\/\/maderamen.com.ar\/dyf-muebles\/?p=12208"},"modified":"2019-12-13T11:20:21","modified_gmt":"2019-12-13T14:20:21","slug":"metalurgica-tesei-soportes-invisibles","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/","title":{"rendered":"Metal\u00fargica Tesei lanz\u00f3 al mercado soportes invisibles para estantes de madera"},"content":{"rendered":"<p><strong>Metal\u00fargica Tesei soportes invisibles: D&amp;F Muebles fue recibido por los hermanos Federico y David Fern\u00e1ndez, socios gerentes de <a href=\"https:\/\/maderamen.com.ar\/dyf-muebles\/empresas\/metalurgica-tesei\/\" target=\"_blank\" rel=\"noopener noreferrer\">Metal\u00fargica Tesei S.A<\/a>. Esta empresa ubicada en la localidad bonaerense de Hurlingham ha lanzado al mercado soportes para estantes de madera que tienen la particularidad de ser \u201cinvisibles\u201d tras su colocaci\u00f3n. Federico Fern\u00e1ndez fue el encargado de responder las consultas period\u00edsticas.<\/strong><\/p>\n<p><strong>&#8211; La empresa cuenta con trayectoria en el sector.<\/strong><\/p>\n<p>&#8211; La empresa cumpli\u00f3 38 a\u00f1os de historia y nosotros estamos al frente desde hace 20 a\u00f1os. Trabajamos con muchos rubros. Uno de ellos es la industria de la madera, que incluye a fabricantes de muebles, de tiranter\u00eda, madereras.<\/p>\n<p>Hacemos productos especiales para desarrollos en madera, dentro de los cuales estamos desarrollando una nueva l\u00ednea de productos. Ya la estamos comercializando en menor escala y la idea es potenciarla: son los soportes invisibles, tal como se los conoce en el mercado. Son soportes que se amuran en la pared y logran que no se vean las m\u00e9nsulas que sostienen la madera. Adem\u00e1s, estamos haciendo una alianza con un cliente para fabricar patas desmontables para sillones, sommiers y camas.<\/p>\n<p>Son productos de muy alta calidad, que resultan de un proceso productivo totalmente automatizado, con muy buen control en el proceso de pintado. Esas caracter\u00edsticas van a diferenciar al producto de lo que existe hoy en plaza.<\/p>\n<figure id=\"attachment_12210\" aria-describedby=\"caption-attachment-12210\" style=\"width: 1400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12210 size-full\" src=\"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2019\/12\/dsc_0456.jpg\" alt=\"metal\u00fargica tesei soportes invisibles \" width=\"1400\" height=\"788\" \/><figcaption id=\"caption-attachment-12210\" class=\"wp-caption-text\">David y Federico Fern\u00e1ndez, socios gerentes de Metal\u00fargica Tesei S.A<\/figcaption><\/figure>\n<p><strong>&#8211; \u00bfEn qu\u00e9 presentaciones comercializan los soportes invisibles?<\/strong><\/p>\n<p>&#8211; Son piezas met\u00e1licas de tres largos (ver recuadro), que es lo que nos solicit\u00f3 el mercado. Los productos se colocan en la pared y van insertos internamente en estantes de madera.<\/p>\n<p>Nosotros vendemos los blisters en los que se incluyen el soporte -un juego de dos unidades-, con sus tarugos correspondientes y arandelas para colocar en la pared. Una vez colocado el estante, no se visualiza c\u00f3mo est\u00e1 sujeto. Por eso se los llama invisibles, ya que el soporte queda dentro del estante.<\/p>\n<p><strong>&#8211; \u00bfDe qu\u00e9 medidas son?<\/strong><\/p>\n<p>&#8211; Hay 50 mil\u00edmetros que ingresan en la pared y despu\u00e9s quedan, seg\u00fan el producto, 100 mil\u00edmetros \u00fatiles, 150 mil\u00edmetros \u00fatiles y hasta 200 mil\u00edmetros \u00fatiles.<\/p>\n<p><strong>&#8211; \u00bfSe sabe hasta qu\u00e9 peso pueden soportar?<\/strong><\/p>\n<figure id=\"attachment_12211\" aria-describedby=\"caption-attachment-12211\" style=\"width: 357px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12211 size-full\" src=\"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2019\/12\/tarugo-invisible.jpg\" alt=\"metal\u00fargica tesei soportes invisibles \" width=\"357\" height=\"141\" \/><figcaption id=\"caption-attachment-12211\" class=\"wp-caption-text\">50 mil\u00edmetros que ingresan en la pared y despu\u00e9s quedan, seg\u00fan el producto, hasta 200 mil\u00edmetros \u00fatiles<\/figcaption><\/figure>\n<p>&#8211; S\u00ed, hicimos un ensayo funcional y el soporte m\u00e1s largo tolera hasta 70 kilogramos. En funci\u00f3n de las necesidades del mercado fuimos desarrollando este nuevo producto.<\/p>\n<p>Notamos que los productos que hab\u00eda en el mercado, a excepci\u00f3n de los importados, eran bastante r\u00fasticos y entonces presentamos una pieza mecanizada de barra hexagonal. Es un producto muy prolijo, que tiene un acabado superficial de calidad.<\/p>\n<p><strong>&#8211; \u00bfEste producto se suma a la l\u00ednea de tirafondos y tornillos que la empresa provee para la industria del mueble?<\/strong><\/p>\n<p>&#8211; S\u00ed. Es un producto nuevo, m\u00e1s all\u00e1 de los tornillos para madera, bulones para ensamblaje de camas y de muebles juveniles, tuercas especiales. Fabricamos l\u00edneas de productos para muebles desarmables que se venden en grandes superficies.<\/p>\n<p>Tenemos tuercas especiales, que son desarmables y que normalmente se importaban. Desarrollamos matrices argentinas para poder inyectar ese tipo de tuercas.<\/p>\n<p><strong>&#8211; Escuch\u00e9 que incorporaron un tratamiento t\u00e9rmico para las piezas.<\/strong><\/p>\n<p>&#8211; S\u00ed, es un punto fundamental. En Argentina se ha ido deteriorando la calidad de los procesos por falta de inversi\u00f3n desde hace muchos a\u00f1os y desde marzo de 2019 incorporamos a un proveedor que tom\u00f3 la decisi\u00f3n de cerrar.<\/p>\n<p>Como esta firma ten\u00eda un proceso de muy buena calidad, mi hermano tom\u00f3 la iniciativa de hacer un convenio con ellos para absorber la empresa. \u00c9l hoy est\u00e1 al frente de esa empresa. La idea es, en alg\u00fan momento, unificar a esa firma dentro del predio de Hurlingham, donde funciona Metal\u00fargica Tesei.<\/p>\n<p><strong>&#8211; Sin ser especialista en el rubro, da la impresi\u00f3n que esa incorporaci\u00f3n les da un plus diferenciador.<\/strong><\/p>\n<p>&#8211; Totalmente. Para nosotros era un gran problema el proceso de tratamiento t\u00e9rmico por la cantidad de falencias que ten\u00eda. Ten\u00edamos un alto porcentaje de rechazo de nuestros proveedores. Nosotros control\u00e1bamos todo lo que recib\u00edamos y el porcentaje de rechazo era muy alto, lo que generaba temas log\u00edsticos, reprocesos, tiempo y dem\u00e1s.<\/p>\n<p>Entonces, fue una decisi\u00f3n estrat\u00e9gica. Comercialmente, para nosotros es como incorporar una m\u00e1quina m\u00e1s al proceso. La realidad \u00e9sa. Cerramos gran parte de nuestro proceso productivo. Y aseguramos la calidad. No nos importa tanto el costo del proceso, sino la calidad. Hoy estamos teniendo rechazo cero, dir\u00eda.<\/p>\n<p><strong>&#8211; \u00bfCu\u00e1l es la cadena de distribuci\u00f3n con la que trabajan?<\/strong><\/p>\n<p>&#8211; Nosotros trabajamos con distribuidores no exclusivos y entonces podemos vender directamente al p\u00fablico, si se da la oportunidad. Tenemos presencia en las provincias, ya que de dos a tres veces por semana entregamos mercader\u00eda en los transportes expreso que nos indiquen los clientes. Hay un volumen m\u00ednimo de venta para poder absorber los costos log\u00edsticos.<\/p>\n<h4><strong>Metal\u00fargica Tesei soportes invisibles: medidas de los soportes invisibles para estantes de madera<\/strong><\/h4>\n<figure id=\"attachment_12212\" aria-describedby=\"caption-attachment-12212\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12212 size-full\" src=\"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2019\/12\/img_2046.jpg\" alt=\"metal\u00fargica tesei soportes invisibles \" width=\"640\" height=\"308\" \/><figcaption id=\"caption-attachment-12212\" class=\"wp-caption-text\">El ensayo funcional indica que el soporte m\u00e1s largo tolera hasta 70 kilogramos<\/figcaption><\/figure>\n<p>Las medidas en las que se presentan los soportes invisibles son las siguientes:<\/p>\n<p>&#8211; Soporte Hexagonal de 10 mm x 150 mm con arandela y tarugo n\u00b010;<\/p>\n<p>&#8211; Soporte Hexagonal de 10 mm x 200 mm con arandela y tarugo n\u00b010;<\/p>\n<p>&#8211; Soporte Hexagonal de 10 mm x 250 mm con arandela y tarugo n\u00b010<\/p>\n<p>Los largos \u00fatiles son de 10 cent\u00edmetros, 15 cent\u00edmetros y 20 cent\u00edmetros.<\/p>\n<p>Contacto: <a href=\"mailto:info@metalurgicatesei.com.ar\" target=\"_blank\" rel=\"noopener noreferrer\">info@metalurgicatesei.com.ar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Metal\u00fargica Tesei soportes invisibles: D&amp;F Muebles fue recibido por los hermanos Federico y David Fern\u00e1ndez, socios gerentes de Metal\u00fargica Tesei S.A. Esta empresa ubicada en la localidad bonaerense de Hurlingham ha lanzado al mercado soportes para estantes de madera que tienen la particularidad de ser \u201cinvisibles\u201d tras su colocaci\u00f3n. Federico Fern\u00e1ndez fue el encargado de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":12209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,23],"tags":[],"class_list":{"0":"post-12208","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-empresariales","8":"category-featured"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Metal\u00fargica Tesei: soportes invisibles para estantes de madera<\/title>\n<meta name=\"description\" content=\"Metal\u00fargica Tesei lanz\u00f3 al mercado soportes para estantes de madera que tienen la particularidad de ser \u201cinvisibles\u201d tras su colocaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metal\u00fargica Tesei: soportes invisibles para estantes de madera\" \/>\n<meta property=\"og:description\" content=\"Metal\u00fargica Tesei lanz\u00f3 al mercado soportes para estantes de madera que tienen la particularidad de ser \u201cinvisibles\u201d tras su colocaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/\" \/>\n<meta property=\"og:site_name\" content=\"D&amp;F Muebles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-13T14:20:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-13T14:20:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2019\/12\/estantes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"936\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/c05f216a5663a04adfc7d62d87295459\"},\"headline\":\"Metal\u00fargica Tesei lanz\u00f3 al mercado soportes invisibles para estantes de madera\",\"datePublished\":\"2019-12-13T14:20:20+00:00\",\"dateModified\":\"2019-12-13T14:20:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/\"},\"wordCount\":993,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/12\\\/estantes.jpg\",\"articleSection\":[\"Empresariales\",\"Principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/\",\"name\":\"Metal\u00fargica Tesei: soportes invisibles para estantes de madera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/12\\\/estantes.jpg\",\"datePublished\":\"2019-12-13T14:20:20+00:00\",\"dateModified\":\"2019-12-13T14:20:21+00:00\",\"description\":\"Metal\u00fargica Tesei lanz\u00f3 al mercado soportes para estantes de madera que tienen la particularidad de ser \u201cinvisibles\u201d tras su colocaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/12\\\/estantes.jpg\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/12\\\/estantes.jpg\",\"width\":1400,\"height\":936,\"caption\":\"metal\u00fargica tesei soportes invisibles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/2019\\\/12\\\/13\\\/metalurgica-tesei-soportes-invisibles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Metal\u00fargica Tesei lanz\u00f3 al mercado soportes invisibles para estantes de madera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"name\":\"D&F Muebles\",\"description\":\"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/09\\\/logo-maderamen-s.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/#\\\/schema\\\/person\\\/c05f216a5663a04adfc7d62d87295459\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/dyf-muebles\\\/author\\\/maderamenadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Metal\u00fargica Tesei: soportes invisibles para estantes de madera","description":"Metal\u00fargica Tesei lanz\u00f3 al mercado soportes para estantes de madera que tienen la particularidad de ser \u201cinvisibles\u201d tras su colocaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/","og_locale":"es_ES","og_type":"article","og_title":"Metal\u00fargica Tesei: soportes invisibles para estantes de madera","og_description":"Metal\u00fargica Tesei lanz\u00f3 al mercado soportes para estantes de madera que tienen la particularidad de ser \u201cinvisibles\u201d tras su colocaci\u00f3n.","og_url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/","og_site_name":"D&amp;F Muebles","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2019-12-13T14:20:20+00:00","article_modified_time":"2019-12-13T14:20:21+00:00","og_image":[{"width":1400,"height":936,"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2019\/12\/estantes.jpg","type":"image\/jpeg"}],"author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/c05f216a5663a04adfc7d62d87295459"},"headline":"Metal\u00fargica Tesei lanz\u00f3 al mercado soportes invisibles para estantes de madera","datePublished":"2019-12-13T14:20:20+00:00","dateModified":"2019-12-13T14:20:21+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/"},"wordCount":993,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/#primaryimage"},"thumbnailUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2019\/12\/estantes.jpg","articleSection":["Empresariales","Principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/","name":"Metal\u00fargica Tesei: soportes invisibles para estantes de madera","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/#primaryimage"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/#primaryimage"},"thumbnailUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2019\/12\/estantes.jpg","datePublished":"2019-12-13T14:20:20+00:00","dateModified":"2019-12-13T14:20:21+00:00","description":"Metal\u00fargica Tesei lanz\u00f3 al mercado soportes para estantes de madera que tienen la particularidad de ser \u201cinvisibles\u201d tras su colocaci\u00f3n.","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/#primaryimage","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2019\/12\/estantes.jpg","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2019\/12\/estantes.jpg","width":1400,"height":936,"caption":"metal\u00fargica tesei soportes invisibles"},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/2019\/12\/13\/metalurgica-tesei-soportes-invisibles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/dyf-muebles\/"},{"@type":"ListItem","position":2,"name":"Metal\u00fargica Tesei lanz\u00f3 al mercado soportes invisibles para estantes de madera"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#website","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","name":"D&F Muebles","description":"Noticias sobre Dise\u00f1o y Fabricaci\u00f3n de muebles en madera","publisher":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/dyf-muebles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","contentUrl":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-content\/uploads\/sites\/4\/2017\/09\/logo-maderamen-s.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/dyf-muebles\/#\/schema\/person\/c05f216a5663a04adfc7d62d87295459","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/dyf-muebles\/author\/maderamenadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/12208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/comments?post=12208"}],"version-history":[{"count":0,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/posts\/12208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media\/12209"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/media?parent=12208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/categories?post=12208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/dyf-muebles\/wp-json\/wp\/v2\/tags?post=12208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}