{"id":6741,"date":"2013-03-06T00:00:00","date_gmt":"2013-03-06T00:00:00","guid":{"rendered":"http:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/"},"modified":"2013-03-06T00:00:00","modified_gmt":"2013-03-06T00:00:00","slug":"ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/","title":{"rendered":"II Jornadas Forestales de Patagonia Sur: se extendi\u00f3 el plazo para recibir trabajos"},"content":{"rendered":"<p>(Buenos Aires, 6 de marzo de 2013). Los eventos II Jornadas Forestales de Patagonia Sur y 2\u00b0 Congreso Internacional Agroforestal Patag\u00f3nico, se desarrollar\u00e1n el 16 y 17 de mayo en El Calafate, Santa Cruz. La organizaci\u00f3n inform\u00f3 a Desarrollo Forestal que se extendi\u00f3 hasta el 30 de marzo para presentar trabajos. Las Jornadas incluir\u00e1n conferencias y sesiones orales de trabajos voluntarios. Asimismo, existir\u00e1 la posibilidad de presentar p\u00f3sters, stands u otros medios gr\u00e1ficos para ser difundidos durante el evento. Las sesiones orales ser\u00e1n elegidas por la Comisi\u00f3n Organizadora bajo recomendaci\u00f3n del Comit\u00e9 Evaluador. M\u00e1s en http:\/\/jornadasforestales2013.unpa.edu.ar\/<\/p>\n<p>Las II Jornadas Forestales de Patagonia Sur y el 2\u00b0 Congreso Internacional Agroforestal Patag\u00f3nico se realizar\u00e1n en El Calafate, Santa Cruz el jueves 16 y viernes 17 de mayo en Hotel Posada Los \u00c1lamos (www.posadalosalamos.com). <\/p>\n<p>La fecha l\u00edmite de entrega de los trabajos completos es el 30 de abril, informaron fuentes de la organizaci\u00f3n. <\/p>\n<p>Pautas y protocolo del evento <\/p>\n<p>Las Jornadas incluir\u00e1n conferencias y sesiones orales de trabajos voluntarios. Asimismo, existir\u00e1 la posibilidad de presentar p\u00f3sters, stands u otros medios gr\u00e1ficos para ser difundidos durante el evento. Las sesiones orales ser\u00e1n elegidas por la Comisi\u00f3n Organizadora bajo recomendaci\u00f3n del Comit\u00e9 Evaluador.  <\/p>\n<p>Las conferencias ser\u00e1n brindadas por especialistas o personalidades del sector forestal bajo invitaci\u00f3n de la Comisi\u00f3n Organizadora del evento. Tambi\u00e9n existir\u00e1 la posibilidad de presentar simposios de 3 horas de duraci\u00f3n, dentro de los cuales el Comit\u00e9 Evaluador seleccionar\u00e1 a cuatro para la apertura del evento. <\/p>\n<p>Como producto del evento se generar\u00e1 un libro de Actas con res\u00famenes expandidos y se editar\u00e1 una publicaci\u00f3n (editorial a definir) con trabajos completos seleccionados. <\/p>\n<p>Los avances y noticias relacionadas con este evento podr\u00e1n consultarse en la p\u00e1gina oficial de las jornadas y las p\u00e1ginas de Internet de las instituciones organizadoras: portal oficial del evento: jornadasforestales2013.unpa.edu.ar <\/p>\n<p>Comit\u00e9 Evaluador <\/p>\n<p>&#8211; Msc. H\u00e9ctor Bahamonde (INTA-UNPA) <br \/>&#8211; Dr. Marcelo Barrera (UNLP) <br \/>&#8211; Ing. Gonzalo Caball\u00e9 (INTA Bariloche) <br \/>&#8211; Dr. Juan Manuel Cellini (UNLP) <br \/>&#8211; Dr. Luis Chauchard (APN Universidad Nacional del Comahue) <br \/>&#8211; Dra. Rosina Soler Esteban (CADIC CONICET) <br \/>&#8211; Dr. Mar\u00eda Elena Fern\u00e1ndez (CONICET-EEA INTA Balcarce, AER Tandil) <br \/>&#8211; Dra. Ver\u00f3nica Gargaglione (INTA-UNPA) <br \/>&#8211; Dr. Javier Gyenge (CONICET &#8211; INTA AER Tandil) <br \/>&#8211; Dra. Lencinas, Mar\u00eda Vanessa (CADIC CONICET) <br \/>&#8211; Dr. Guillermo Mart\u00ednez Pastur (CADIC- CONICET) <br \/>&#8211; Dr. Mario Pastorino (CONICET EEA INTA Bariloche) <br \/>&#8211; PhD. Pablo Luis Peri (INTA EEA Santa Cruz- UNPA- CONICET) <\/p>\n<p>Inscripciones <\/p>\n<p>Para inscribirse en las II Jornadas Forestales cada participante deber\u00e1 llenar el formulario al que se puede acceder en la pagina oficial de las jornadas (http:\/\/jornadasforestales2013.unpa.edu.ar\/), adjuntando el comprobante de pago de <br \/>la inscripci\u00f3n (escaneado). Se confirmar\u00e1 la inscripci\u00f3n a cada participante v\u00eda <br \/>correo electr\u00f3nico. <\/p>\n<p>Costos de Inscripci\u00f3n: <\/p>\n<p>El costo de las inscripciones es de $700 (pesos argentinos) para participantes, $600 para aquellos que presentan trabajos y $200 para estudiantes. <\/p>\n<p>Datos de la cuenta bancaria para realizar el pago: <br \/>&#8211; Raz\u00f3n Social: Fundaci\u00f3n ArgenINTA \u2013 Delegaci\u00f3n Patagonia Sur <br \/>&#8211; CUIT: 30-67630365-7 <br \/>&#8211; Banco: Banco de la Naci\u00f3n Argentina <br \/>&#8211; Tipo de cuenta: Cuenta Corriente (Cta.Cte.) <br \/>&#8211; N\u00b0 de cuenta: 52.400.370\/39 <br \/>&#8211; CBU: 01105247-20052400370395 <br \/>&#8211; Nota: Estos datos bancarios tambi\u00e9n son v\u00e1lidos para que los participantes extranjeros puedan efectuar el pago de la inscripci\u00f3n. <\/p>\n<p>\u00c1reas tem\u00e1ticas <\/p>\n<p>Para estas Jornadas se han definido 6 grandes \u00e1reas tem\u00e1ticas en las que se repartir\u00e1n las conferencias y sesiones orales de trabajos voluntarios. Las \u00e1reas definidas son: <\/p>\n<p>&#8211; (1) Legislaci\u00f3n, enfoque pol\u00edtico y uso social del bosque. <\/p>\n<p>&#8211; (2) Industria y certificaci\u00f3n forestal. <\/p>\n<p>&#8211; (3) Ecolog\u00eda y sanidad forestal de los bosques nativos. <\/p>\n<p>&#8211; (4) Silvicultura del bosque nativo. <\/p>\n<p>&#8211; (5) Ecolog\u00eda y silvicultura de plantaciones de especies ex\u00f3ticas. <\/p>\n<p>&#8211; (6) Silvicultura y manejo de sistemas agroforestales en ambientes de la Patagonia. <\/p>\n<p>Presentaci\u00f3n de res\u00famenes expandidos <\/p>\n<p>Los res\u00famenes se presentar\u00e1n de acuerdo a las normas de autor. El nombre del archivo deber\u00e1 contener el apellido y nombre del autor inscripto, as\u00ed como indicar si es un trabajo para las II Jornadas Forestales Patag\u00f3nicas (JFP) o para el 2\u00ba Congreso Internacional Agroforestal (AGFO) separado por un gui\u00f3n bajo. (Ejemplo: JFP_JuanGonzales.doc; AGFO_LucasMonelos.doc). <\/p>\n<p>Para enviar el trabajo deber\u00e1: armar un archivo Zip que contendr\u00e1 el resumen expandido en formato Word y otro archivo con la tabla o figura, en el caso que corresponda. El archivo comprimido deber\u00e1 cargarse o adjuntarse en la p\u00e1gina oficial de las jornadas respetando las especificaciones detalladas en el apartado \u201cNormas de autor\u201d. Cada participante podr\u00e1 presentar m\u00e1s de un trabajo. <\/p>\n<p>Normas de Autor para res\u00famenes expandidos: <br \/>&#8211; Longitud: el resumen expandido (texto + figura o tabla) no debe superar una pagina A4 con m\u00e1rgenes izquierdo 3 cm, el resto de los m\u00e1rgenes de 2,5 cm. <br \/>&#8211; T\u00edtulo: Letra Times New Roman, tama\u00f1o 14 Negrita, primera letra con may\u00fascula, Nombres cient\u00edficos en cursiva sin subrayar. Sin punto final. 150 caracteres m\u00e1ximo. Dicho texto debe estar centrado. <br \/>&#8211; Autores: Letra Times New Roman, tama\u00f1o 12. Apellidos e iniciales de nombres <br \/>separados con punto y coma entre autores. Seguido de lugar de trabajo, direcci\u00f3n postal y direcci\u00f3n electr\u00f3nica del primer autor, en letra Times New Roman tama\u00f1o 10. Dicho texto debe estar centrado. <br \/>&#8211; Cuerpo: Letra Times New Roman, tama\u00f1o 12. Se debe describir el trabajo en no m\u00e1s de 500 palabras, donde consten brevemente una introducci\u00f3n, un objetivo y resultados del trabajo. Dicho texto debe estar justificado. <br \/>&#8211; Palabras claves: debe contener al menos 3 (tres) palabras claves que sugieran la tem\u00e1tica que aborda el trabajo presentado y que no est\u00e9n contenido en el t\u00edtulo. <br \/>&#8211; Tabla: Se confeccionar\u00e1 en Microsoft Word. Se titular\u00e1 en la parte superior con tama\u00f1o de letras y n\u00fameros legibles. <br \/>&#8211; Figura: Deber\u00e1 enviarse en archivo de imagen jpg, con una resoluci\u00f3n no menor a 300 DPI, lista para copiar y pegar. Se titular\u00e1 en la parte inferior con tama\u00f1o de letras y n\u00fameros legibles y no deben incluir el t\u00edtulo. <br \/>&#8211; Las Figuras y Tablas deben realizarse en blanco y negro (no usar grises). <br \/>&#8211; Se recuerda a los participantes dejar el espacio en el cuerpo del texto para que el trabajo no supere el tama\u00f1o establecido de una hoja tama\u00f1o A4. Se adjunta en Internet un ejemplo de resumen expandido. <\/p>\n<p>Propuesta de Simposio <\/p>\n<p>Para la recepci\u00f3n de las propuestas de simposio, las mismas deber\u00e1n contener:  <br \/>1- T\u00edtulo de Propuesta de Simposio; <br \/>2- Organizadores;  <br \/>3- Duraci\u00f3n Propuesta; <br \/>4- Financiamiento, <br \/>5- Objetivos; <br \/>6- Importancia del Simposio;  <br \/>7- Ponentes invitados. <\/p>\n<p>Entidades organizadoras <\/p>\n<p>&#8211; EEA INTA Santa Cruz <\/p>\n<p>&#8211; Grupo de Recursos Forestales del Centro Austral de Investigaciones Cient\u00edficas (CADIC-CONICET) <\/p>\n<p>&#8211; Universidad Nacional de la Patagonia Austral (UNPA) <\/p>\n<p>-Direcci\u00f3n de Bosques- Consejo Agrario Provincial (CAP) <\/p>\n<p>&#8211; Secretar\u00eda de Medio Ambiente y Desarrollo Sustentable de Naci\u00f3n <\/p>\n<p>&#8211; Instituto Forestal &#8211; sedes: BioBio y Patagonia &#8211; Chile (INFOR) <\/p>\n<p>&#8211; Direcci\u00f3n General de Bosques de Tierra del Fuego. <\/p>\n<p>&#8211; EEA INTA Esquel <\/p>\n<p>&#8211; Direcci\u00f3n de Producci\u00f3n Forestal &#8211; Ministerio de Agricultura (MINAGRI) <\/p>\n<p>Comisi\u00f3n organizadora <\/p>\n<p>&#8211; Presidente: PhD. Pablo Luis Peri (INTA EEA Santa Cruz- UNPA- CONICET) <\/p>\n<p>&#8211; Secretaria Ejecutiva: Romina G. Lasagno (INTA EEA Santa Cruz) <\/p>\n<p>Integrantes: Dr. Guillermo Mart\u00ednez Pastur (CADIC- CONICET), Miguel Ferro (director de Bosques \u2013 CAP- Santa Cruz), Dr. \u00c1lvaro Sotomayor (INFOR- CHILE Sedes Biobio y Patagonia),  <br \/>Ing. Ftal. Sebasti\u00e1n Fari\u00f1a (Direcci\u00f3n General de Bosques de Tierra del Fuego), Dr. Carlos Buduba (INTA EEA Esquel) <\/p>\n<p>Auspicios institucionales <\/p>\n<p>&#8211; IUFRO Landscape Ecology International Group <\/p>\n<p>&#8211; IUFRO Agroforestry Group <\/p>\n<p>&#8211; CONAF (Corporaci\u00f3n Nacional Forestal de Chile) <\/p>\n<p>&#8211; UMAG (Universidad de Magallanes, Chile) <\/p>\n<p>&#8211; ALUNCOINFO (Asociaci\u00f3n de Lucha Contra Incendios Forestales) <\/p>\n<p>&#8211; Municipalidad de El Calafate &#8211; Provincia de Santa Cruz <\/p>\n<p>Empresas patrocinantes <\/p>\n<p>&#8211; Aserradero Kareken, Tierra del Fuego <\/p>\n<p>&#8211; Bronzovich Hnos. S.R.L., Tierra del Fuego <\/p>\n<p>&#8211; Forestal Russfin Limitada, Chile <\/p>\n<p>&#8211; Monte Alto Forestal, Chile <\/p>\n<p>Objetivos de las Jornadas <\/p>\n<p>Divulgar los resultados y\/o avances t\u00e9cnico-cient\u00edficos de proyectos que incluyan al bosque nativo, a las plantaciones forestales y a los sistemas agroforestales como objeto de estudio, su manejo, ecolog\u00eda y\/o conservaci\u00f3n. <\/p>\n<p>Promover la comunicaci\u00f3n inter-sectorial, as\u00ed como entre instituciones p\u00fablicas y privadas, de alcance internacional, nacional o provincial que tengan injerencia en la Patagonia. <\/p>\n<p>Divulgar herramientas t\u00e9cnicas que mejoren la toma de datos, monitoreo y\/o gesti\u00f3n de los bosques, plantaciones forestales y sistemas agroforestales para su manejo sustentable. <\/p>\n<p>Potenciar, las plantaciones forestales y sistemas agroforestales, incluyendo al sector de la transformaci\u00f3n primaria y secundaria de la actividad forestal para fomentar el desarrollo local o territorial. <\/p>\n<p>Motivar un \u00e1mbito de discusi\u00f3n y reflexi\u00f3n para el desarrollo de la econom\u00eda forestal de Patagonia Sur. <\/p>\n<p>Sitos de inter\u00e9s: <\/p>\n<p>&#8211; INTA EEA Santa Cruz: http:\/\/inta.gob.ar\/unidades\/913000 <\/p>\n<p>&#8211; Grupo de Recursos Forestales del CADIC-CONICET: www.cadic-conicet.gob.ar\/forestales <\/p>\n<p>&#8211; INFOR Chile: www.agroforesteria.cl  <\/p>\n<p>&#8211; Tierra del Fuego (Secretar\u00eda de Desarrollo Sustenbtable): http:\/\/desarrollosustentable.tierradelfuego.gov.ar\/bosques\/bosques\/ <\/p>\n<p>Imagen: Gentileza organizadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Buenos Aires, 6 de marzo de 2013). Los eventos II Jornadas Forestales de Patagonia Sur y 2\u00b0 Congreso Internacional Agroforestal Patag\u00f3nico, se desarrollar\u00e1n el 16 y 17 de mayo en El Calafate, Santa Cruz. La organizaci\u00f3n inform\u00f3 a Desarrollo Forestal que se extendi\u00f3 hasta el 30 de marzo para presentar trabajos. Las Jornadas incluir\u00e1n conferencias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-6741","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ferias-y-congresos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>II Jornadas Forestales de Patagonia Sur: se extendi\u00f3 el plazo para recibir trabajos - Desarrollo Forestal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"II Jornadas Forestales de Patagonia Sur: se extendi\u00f3 el plazo para recibir trabajos - Desarrollo Forestal\" \/>\n<meta property=\"og:description\" content=\"(Buenos Aires, 6 de marzo de 2013). Los eventos II Jornadas Forestales de Patagonia Sur y 2\u00b0 Congreso Internacional Agroforestal Patag\u00f3nico, se desarrollar\u00e1n el 16 y 17 de mayo en El Calafate, Santa Cruz. La organizaci\u00f3n inform\u00f3 a Desarrollo Forestal que se extendi\u00f3 hasta el 30 de marzo para presentar trabajos. Las Jornadas incluir\u00e1n conferencias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/\" \/>\n<meta property=\"og:site_name\" content=\"Desarrollo Forestal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-06T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2013\\\/03\\\/06\\\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2013\\\/03\\\/06\\\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\"},\"headline\":\"II Jornadas Forestales de Patagonia Sur: se extendi\u00f3 el plazo para recibir trabajos\",\"datePublished\":\"2013-03-06T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2013\\\/03\\\/06\\\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\\\/\"},\"wordCount\":1569,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\"},\"articleSection\":[\"Ferias y Congresos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2013\\\/03\\\/06\\\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2013\\\/03\\\/06\\\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2013\\\/03\\\/06\\\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\\\/\",\"name\":\"II Jornadas Forestales de Patagonia Sur: se extendi\u00f3 el plazo para recibir trabajos - Desarrollo Forestal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#website\"},\"datePublished\":\"2013-03-06T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2013\\\/03\\\/06\\\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2013\\\/03\\\/06\\\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2013\\\/03\\\/06\\\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"II Jornadas Forestales de Patagonia Sur: se extendi\u00f3 el plazo para recibir trabajos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\",\"name\":\"Desarrollo Forestal\",\"description\":\"Noticias del sector forestal\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/maderamen-emago.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/maderamen-emago.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/author\\\/sachi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"II Jornadas Forestales de Patagonia Sur: se extendi\u00f3 el plazo para recibir trabajos - Desarrollo Forestal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/","og_locale":"es_ES","og_type":"article","og_title":"II Jornadas Forestales de Patagonia Sur: se extendi\u00f3 el plazo para recibir trabajos - Desarrollo Forestal","og_description":"(Buenos Aires, 6 de marzo de 2013). Los eventos II Jornadas Forestales de Patagonia Sur y 2\u00b0 Congreso Internacional Agroforestal Patag\u00f3nico, se desarrollar\u00e1n el 16 y 17 de mayo en El Calafate, Santa Cruz. La organizaci\u00f3n inform\u00f3 a Desarrollo Forestal que se extendi\u00f3 hasta el 30 de marzo para presentar trabajos. Las Jornadas incluir\u00e1n conferencias [&hellip;]","og_url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/","og_site_name":"Desarrollo Forestal","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2013-03-06T00:00:00+00:00","author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343"},"headline":"II Jornadas Forestales de Patagonia Sur: se extendi\u00f3 el plazo para recibir trabajos","datePublished":"2013-03-06T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/"},"wordCount":1569,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization"},"articleSection":["Ferias y Congresos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/","name":"II Jornadas Forestales de Patagonia Sur: se extendi\u00f3 el plazo para recibir trabajos - Desarrollo Forestal","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#website"},"datePublished":"2013-03-06T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2013\/03\/06\/ii-jornadas-forestales-de-patagonia-sur-se-extendio-el-plazo-para-recibir-trabajos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/"},{"@type":"ListItem","position":2,"name":"II Jornadas Forestales de Patagonia Sur: se extendi\u00f3 el plazo para recibir trabajos"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#website","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/","name":"Desarrollo Forestal","description":"Noticias del sector forestal","publisher":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2026\/03\/maderamen-emago.png","contentUrl":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2026\/03\/maderamen-emago.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/author\/sachi\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts\/6741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/comments?post=6741"}],"version-history":[{"count":0,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts\/6741\/revisions"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/media?parent=6741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/categories?post=6741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/tags?post=6741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}