{"id":6557,"date":"2011-07-21T00:00:00","date_gmt":"2011-07-21T00:00:00","guid":{"rendered":"http:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/"},"modified":"2011-07-21T00:00:00","modified_gmt":"2011-07-21T00:00:00","slug":"argenplas-2012-xiv-exposicion-internacional-de-plasticos","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/","title":{"rendered":"Argenpl\u00e1s 2012, XIV Exposici\u00f3n Internacional de Pl\u00e1sticos"},"content":{"rendered":"<p>Argenpl\u00e1s 2012 renueva su condici\u00f3n de cita obligada a nivel mundial para hacer negocios expositores y visitantes profesionales, tomadores de decisi\u00f3n e inversionistas, informaron desde la organizaci\u00f3n. La feria se desarrollar\u00e1 del 18 al 22 de junio pr\u00f3ximo en el predio Costa Salguero de la Capital Federal. Organizan Reed Exhibitions, Alcantara Machado Feiras de Negocios y la C\u00e1mara Argentina de la Industria Pl\u00e1stica (CAIP), mientras que  Editorial Emma Fiorentino est\u00e1 encargada de la edici\u00f3n del cat\u00e1logo oficial.<\/p>\n<p>Argenpl\u00e1s 2012 es una cita de profesionales con un perfil seleccionado para brindar al expositor un ambiente favorable para hacer negocios como empresarios, ejecutivos, ingenieros, t\u00e9cnicos y profesionales relacionados con el sector: fabricantes, transformadores y usuarios de productos pl\u00e1sticos; transformadores de materias primas; personas de niveles gerenciales, tecnolog\u00eda y producci\u00f3n y marketing de la industria automotriz y transporte, construcci\u00f3n, ingenier\u00eda, telecomunicaciones, productos para el hogar, laboratorios y packaging, entre muchos otros. <\/p>\n<p>Expondr\u00e1n empresas de los siguientes rubros: M\u00e1quinas y Equipamientos; Automaci\u00f3n y Control; Instrumentaci\u00f3n para Control de Calidad; Moldes, Matrices y Herramientas; Materias Primas; Productos Qu\u00edmicos y Auxiliares; Transformadores de Pl\u00e1stico; Productos Terminados y Semi Elaborados; Medio Ambiente y Reciclaje; Instituciones, Bancos, Servicios y Publicaciones T\u00e9cnicas. <\/p>\n<p>Contacto: Mara Alterni y Emma Fiorentino al (54-11) 4943-0090 o escribiendo a emmafiorentino@fibertel.com.ar o a info@emmafiorentino.com.ar o visitando www.emmafiorentino.com.ar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Argenpl\u00e1s 2012 renueva su condici\u00f3n de cita obligada a nivel mundial para hacer negocios expositores y visitantes profesionales, tomadores de decisi\u00f3n e inversionistas, informaron desde la organizaci\u00f3n. La feria se desarrollar\u00e1 del 18 al 22 de junio pr\u00f3ximo en el predio Costa Salguero de la Capital Federal. Organizan Reed Exhibitions, Alcantara Machado Feiras de Negocios [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-6557","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ferias-y-congresos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Argenpl\u00e1s 2012, XIV Exposici\u00f3n Internacional de Pl\u00e1sticos - Desarrollo Forestal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Argenpl\u00e1s 2012, XIV Exposici\u00f3n Internacional de Pl\u00e1sticos - Desarrollo Forestal\" \/>\n<meta property=\"og:description\" content=\"Argenpl\u00e1s 2012 renueva su condici\u00f3n de cita obligada a nivel mundial para hacer negocios expositores y visitantes profesionales, tomadores de decisi\u00f3n e inversionistas, informaron desde la organizaci\u00f3n. La feria se desarrollar\u00e1 del 18 al 22 de junio pr\u00f3ximo en el predio Costa Salguero de la Capital Federal. Organizan Reed Exhibitions, Alcantara Machado Feiras de Negocios [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/\" \/>\n<meta property=\"og:site_name\" content=\"Desarrollo Forestal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-21T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2011\\\/07\\\/21\\\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2011\\\/07\\\/21\\\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\"},\"headline\":\"Argenpl\u00e1s 2012, XIV Exposici\u00f3n Internacional de Pl\u00e1sticos\",\"datePublished\":\"2011-07-21T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2011\\\/07\\\/21\\\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\\\/\"},\"wordCount\":249,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\"},\"articleSection\":[\"Ferias y Congresos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2011\\\/07\\\/21\\\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2011\\\/07\\\/21\\\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2011\\\/07\\\/21\\\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\\\/\",\"name\":\"Argenpl\u00e1s 2012, XIV Exposici\u00f3n Internacional de Pl\u00e1sticos - Desarrollo Forestal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#website\"},\"datePublished\":\"2011-07-21T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2011\\\/07\\\/21\\\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2011\\\/07\\\/21\\\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2011\\\/07\\\/21\\\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Argenpl\u00e1s 2012, XIV Exposici\u00f3n Internacional de Pl\u00e1sticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\",\"name\":\"Desarrollo Forestal\",\"description\":\"Noticias del sector forestal\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/maderamen-emago.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/maderamen-emago.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/author\\\/sachi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Argenpl\u00e1s 2012, XIV Exposici\u00f3n Internacional de Pl\u00e1sticos - Desarrollo Forestal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/","og_locale":"es_ES","og_type":"article","og_title":"Argenpl\u00e1s 2012, XIV Exposici\u00f3n Internacional de Pl\u00e1sticos - Desarrollo Forestal","og_description":"Argenpl\u00e1s 2012 renueva su condici\u00f3n de cita obligada a nivel mundial para hacer negocios expositores y visitantes profesionales, tomadores de decisi\u00f3n e inversionistas, informaron desde la organizaci\u00f3n. La feria se desarrollar\u00e1 del 18 al 22 de junio pr\u00f3ximo en el predio Costa Salguero de la Capital Federal. Organizan Reed Exhibitions, Alcantara Machado Feiras de Negocios [&hellip;]","og_url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/","og_site_name":"Desarrollo Forestal","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2011-07-21T00:00:00+00:00","author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343"},"headline":"Argenpl\u00e1s 2012, XIV Exposici\u00f3n Internacional de Pl\u00e1sticos","datePublished":"2011-07-21T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/"},"wordCount":249,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization"},"articleSection":["Ferias y Congresos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/","name":"Argenpl\u00e1s 2012, XIV Exposici\u00f3n Internacional de Pl\u00e1sticos - Desarrollo Forestal","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#website"},"datePublished":"2011-07-21T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2011\/07\/21\/argenplas-2012-xiv-exposicion-internacional-de-plasticos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/"},{"@type":"ListItem","position":2,"name":"Argenpl\u00e1s 2012, XIV Exposici\u00f3n Internacional de Pl\u00e1sticos"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#website","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/","name":"Desarrollo Forestal","description":"Noticias del sector forestal","publisher":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2026\/03\/maderamen-emago.png","contentUrl":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2026\/03\/maderamen-emago.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/author\/sachi\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts\/6557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/comments?post=6557"}],"version-history":[{"count":0,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts\/6557\/revisions"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/media?parent=6557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/categories?post=6557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/tags?post=6557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}