{"id":6233,"date":"2008-09-19T00:00:00","date_gmt":"2008-09-19T00:00:00","guid":{"rendered":"http:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/"},"modified":"2008-09-19T00:00:00","modified_gmt":"2008-09-19T00:00:00","slug":"femasa-srl-e-igh-srl-trayectoria-en-autoelevadores","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/","title":{"rendered":"FEMASA SRL e IGH SRL, trayectoria en autoelevadores"},"content":{"rendered":"<p>FE.MA.SA. SRL lleva m\u00e1s de 20 a\u00f1os fabricando autoelevadores en su planta industrial del Tigre, provincia de Buenos Aires. Esta firma desarroll\u00f3 recientemente un autoelevador todo terreno. Por su parte, I.G.H. SRL produce autoelevadores frontales desde hace 14 a\u00f1os en San Francisco, C\u00f3rdoba. Cuentan con distribuidores en todo el pa\u00eds.<\/p>\n<p>FE.MA.SA. SRL es una empresa con m\u00e1s de 20 a\u00f1os dedicada a la fabricaci\u00f3n de autoelevadores el\u00e9ctricos, tractores de arrastre el\u00e9ctricos y autoelevadores todo terreno con capacidad de carga 1,8 y 2,5 toneladas. Se encuentra ubicada en el partido de Tigre, provincia de Buenos Aires. Tambi\u00e9n es prestadora de servicio y mantenimiento de todas las marcas y modelos de autoelevadores. <\/p>\n<p>En tanto, I.G.H. SRL es una empresa familiar con una experiencia de 14 a\u00f1os en la fabricaci\u00f3n de autoelevadores frontales de 2; 2,5; 3 y 3,5 toneladas. Sus instalaciones est\u00e1n en San Francisco, provincia de C\u00f3rdoba. En I.G.H. tambi\u00e9n se producen, con tecnolog\u00eda de \u00faltima generaci\u00f3n, las transmisiones de todas las m\u00e1quinas fabricadas por ambas empresas, como las cajas de cambio completas, reductoras de ruedas y varios componentes. Modelos fabricados: G20-G25-G30-G35. <\/p>\n<p>FEMASA S.R.L. est\u00e1 ubicada en el partido de Tigre, provincia de Buenos Aires, con lo cual se sit\u00faa muy pr\u00f3xima al Delta del R\u00edo de La Plata. Por ende, sus clientes est\u00e1n dedicados al aserrado de maderas de \u00e1lamo, sauce, saligna y pino. A ellos se les presta el servicio de mantenimiento de sus tractoelevadores; adem\u00e1s, en algunos casos se les ha provisto autoelevadores convencionales. <\/p>\n<p>A partir de 2006 muchos clientes consultaban a esta empresa por la posibilidad de construir un autoelevador todo terreno, capaz de cumplir con las mismas prestaciones de un tractor invertido y con la agilidad de un autoelevador convencional. El objetivo: poder trabajar con \u00e9l en un terreno de tierra y con barro. Con la capacidad de cargar los troncos en los bancos de corte, estibar dentro y fuera de los galpones pilas exteriores, y cargar y descargar equipos. <\/p>\n<p>\u201cEl desaf\u00edo nos gust\u00f3. Por lo tanto, comenzamos por escuchar la necesidad de nuestros clientes y a investigar cu\u00e1l era la forma de trabajar que ten\u00edan: tipos de suelos, volumen de madera, necesidad de despeje del piso, tipos de rodados, inclinaci\u00f3n de la torre hacia adelante y atr\u00e1s para optimizar dos cosas la toma y vuelco de los troncos en los bancos\u201d, se\u00f1alaron fuentes de la empresa. <\/p>\n<p>De esta manera, con todos los datos analizados la f\u00e1brica desarroll\u00f3 un autoelevador todo terreno, que tiene los siguientes datos t\u00e9cnicos: <br \/>&#8211; 1) 1,8 toneladas motor HYUNDAI  A4BB_ 40 HP Industrial 1800 rpm; <br \/>&#8211; 2) 2,5 toneladas motor HYUNDAI A4BBG_ 90 HP Industrial 1800 rpm. Opcional Perkins  4 _ 203. <br \/>&#8211; Caja de velocidades: mec\u00e1nica (alta y baja) adelante, atr\u00e1s; <br \/>&#8211; Eje motriz: diferencial Dana 44, palieres flotantes, reductora mando final planetarios; <br \/>&#8211; M\u00e1stil de elevaci\u00f3n: triple colisa de 5 metros con desplazador lateral; <br \/>&#8211; Hidr\u00e1ulica: Venturi Hermanos SRL; <br \/>&#8211; Frenos: hidr\u00e1ulicos a tambor, di\u00e1metro 450 sobre ruedas motrices, cilindro de rueda Mercedes Benz 1517, bomba de freno Ford 350, freno de mano sobre la caja. <\/p>\n<p>Por su parte, \u00e9stas son las caracter\u00edsticas t\u00e9cnicas del Tractoelevador diesel: <br \/>&#8211; Altura de techo protector desde el piso: 2350 mil\u00edmetros; <br \/>&#8211; Altura del chasis: 1230 mil\u00edmetros; <br \/>&#8211; Distancia entre ejes: 2180 mil\u00edmetros; <br \/>&#8211; Largo parcial hasta cara de u\u00f1as: 3220 mil\u00edmetros; <br \/>&#8211; Largo total hasta extremo de u\u00f1as: 4440 mil\u00edmetros; <br \/>&#8211; Torre triple coliza plegada: 2420 mil\u00edmetros; <br \/>&#8211; Despeje m\u00e1ximo: 340 mil\u00edmetros; <br \/>&#8211; Ancho del tractoelevador: 1710 mil\u00edmetros; <br \/>&#8211; Distancia del desplazador: 115 mil\u00edmetros; <br \/>&#8211; Separaci\u00f3n cara exterior u\u00f1as: 1100 mil\u00edmetros; <br \/>&#8211; Elevaci\u00f3n libre: 1667 mil\u00edmetros; <br \/>&#8211; Elevaci\u00f3n total: 5000 mil\u00edmetros; <br \/>&#8211; Radio de giro: 3300 mil\u00edmetros; <br \/>&#8211; Rodado trasero: 295\/80 R22.5 16 PR; <br \/>&#8211; Rodado delantero 7.00&#215;12. <\/p>\n<p>Distribuidores: <br \/>&#8211; Corrientes-Misiones: Agroforest SRL. Av. San Mart\u00edn 1462, Virasoro, Corrientes. Correo electr\u00f3nico: agroforest@cableat.net <br \/>&#8211; Chaco-Formosa: Maquinagro SRL. Casa central: San Juan 884 (3603), El Colorado, Formosa <br \/>Telefax.: (03717) 480050\/ 480369. Correo electr\u00f3nico: maquinagrorep@coopcolorado.com.ar <br \/>-Sucursal Formosa capital: 25 de Mayo 1201 (3600), Formosa, Formosa. Telefax: (03717) 425516. Correo electr\u00f3nico: maquinagro-fsa@coopcolorado.com.ar <br \/>&#8211; Mendoza, San Juan y San Luis: SSL Servicios San Luis SRL. Av. Lafinur 640 (5700), San Luis, San Luis. Telefax: (02652) 435947. Correo electr\u00f3nico: serviciossanluis@speedy.com.ar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FE.MA.SA. SRL lleva m\u00e1s de 20 a\u00f1os fabricando autoelevadores en su planta industrial del Tigre, provincia de Buenos Aires. Esta firma desarroll\u00f3 recientemente un autoelevador todo terreno. Por su parte, I.G.H. SRL produce autoelevadores frontales desde hace 14 a\u00f1os en San Francisco, C\u00f3rdoba. Cuentan con distribuidores en todo el pa\u00eds. FE.MA.SA. SRL es una empresa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-6233","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-empresariales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FEMASA SRL e IGH SRL, trayectoria en autoelevadores - Desarrollo Forestal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FEMASA SRL e IGH SRL, trayectoria en autoelevadores - Desarrollo Forestal\" \/>\n<meta property=\"og:description\" content=\"FE.MA.SA. SRL lleva m\u00e1s de 20 a\u00f1os fabricando autoelevadores en su planta industrial del Tigre, provincia de Buenos Aires. Esta firma desarroll\u00f3 recientemente un autoelevador todo terreno. Por su parte, I.G.H. SRL produce autoelevadores frontales desde hace 14 a\u00f1os en San Francisco, C\u00f3rdoba. Cuentan con distribuidores en todo el pa\u00eds. FE.MA.SA. SRL es una empresa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Desarrollo Forestal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-09-19T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2008\\\/09\\\/19\\\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2008\\\/09\\\/19\\\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\"},\"headline\":\"FEMASA SRL e IGH SRL, trayectoria en autoelevadores\",\"datePublished\":\"2008-09-19T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2008\\\/09\\\/19\\\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\\\/\"},\"wordCount\":737,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\"},\"articleSection\":[\"Empresariales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2008\\\/09\\\/19\\\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2008\\\/09\\\/19\\\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2008\\\/09\\\/19\\\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\\\/\",\"name\":\"FEMASA SRL e IGH SRL, trayectoria en autoelevadores - Desarrollo Forestal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#website\"},\"datePublished\":\"2008-09-19T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2008\\\/09\\\/19\\\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2008\\\/09\\\/19\\\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2008\\\/09\\\/19\\\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FEMASA SRL e IGH SRL, trayectoria en autoelevadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\",\"name\":\"Desarrollo Forestal\",\"description\":\"Noticias del sector forestal\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/maderamen-emago.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/maderamen-emago.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/person\\\/ad3cdc3df72c15861fdd096bee929343\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/author\\\/sachi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FEMASA SRL e IGH SRL, trayectoria en autoelevadores - Desarrollo Forestal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/","og_locale":"es_ES","og_type":"article","og_title":"FEMASA SRL e IGH SRL, trayectoria en autoelevadores - Desarrollo Forestal","og_description":"FE.MA.SA. SRL lleva m\u00e1s de 20 a\u00f1os fabricando autoelevadores en su planta industrial del Tigre, provincia de Buenos Aires. Esta firma desarroll\u00f3 recientemente un autoelevador todo terreno. Por su parte, I.G.H. SRL produce autoelevadores frontales desde hace 14 a\u00f1os en San Francisco, C\u00f3rdoba. Cuentan con distribuidores en todo el pa\u00eds. FE.MA.SA. SRL es una empresa [&hellip;]","og_url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/","og_site_name":"Desarrollo Forestal","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2008-09-19T00:00:00+00:00","author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343"},"headline":"FEMASA SRL e IGH SRL, trayectoria en autoelevadores","datePublished":"2008-09-19T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/"},"wordCount":737,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization"},"articleSection":["Empresariales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/","name":"FEMASA SRL e IGH SRL, trayectoria en autoelevadores - Desarrollo Forestal","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#website"},"datePublished":"2008-09-19T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2008\/09\/19\/femasa-srl-e-igh-srl-trayectoria-en-autoelevadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/"},{"@type":"ListItem","position":2,"name":"FEMASA SRL e IGH SRL, trayectoria en autoelevadores"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#website","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/","name":"Desarrollo Forestal","description":"Noticias del sector forestal","publisher":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2026\/03\/maderamen-emago.png","contentUrl":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2026\/03\/maderamen-emago.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/person\/ad3cdc3df72c15861fdd096bee929343","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af612dc5cc79b81354fdd5591e3c15e376793953a9585c1142faad6370a6f555?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/author\/sachi\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts\/6233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/comments?post=6233"}],"version-history":[{"count":0,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts\/6233\/revisions"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/media?parent=6233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/categories?post=6233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/tags?post=6233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}