{"id":17880,"date":"2025-12-12T14:56:34","date_gmt":"2025-12-12T17:56:34","guid":{"rendered":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/?p=17880"},"modified":"2026-03-27T19:18:49","modified_gmt":"2026-03-27T22:18:49","slug":"confiar-mesa-foresto-industria-y-brindis","status":"publish","type":"post","link":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/","title":{"rendered":"CONFIAR: Mesa Foresto-Industrial y brindis de fin de a\u00f1o"},"content":{"rendered":"\n<p><strong>El jueves 4 de diciembre a las 19 horas, en el Auditorio de la Sociedad Rural Argentina se llev\u00f3 a cabo el brindis de fin de a\u00f1o organizado por CONFIAR (Consejo Foresto Industrial Argentino). A este le precedi\u00f3 la Mesa Foresto-Industrial en la cual participaron los principales referentes p\u00fablicos y privados del sector. <\/strong><\/p>\n\n\n\n<p>Se sentaron a ella, adem\u00e1s de los representantes de las diferentes c\u00e1maras que integran el consejo: el Subsecretario de Producci\u00f3n Agropecuaria y Forestal, Ing. Manuel Chiappe; y la directora nacional de Desarrollo Foresto-Industrial, Sabina Vetter. De Entre R\u00edos, el ministro de desarrollo econ\u00f3mico Guillermo Bernaudo y la directora forestal, Lorna Sacks. Por Corrientes, el ministro de Producci\u00f3n Claudio Anselmo y el secretario de Desarrollo Foresto-Industrial Luis Mestres. De Misiones, el ministro de Industria Federico Fachinello. Adem\u00e1s, el presidente del INTA, Nicol\u00e1s Bronzovich.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1050\" src=\"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2025\/12\/img_20251204_195459_643_hdr-1.jpg\" alt=\"\" class=\"wp-image-17883\" \/><\/figure>\n\n\n\n<p>El objetivo de la misma era analizar lo alcanzado en el 2025 y las perspectivas del 2026. Luego de las palabras del subsecretario fue el turno de los actores del sector privado y de los representantes de las provincias:<\/p>\n\n\n\n<p>El CEO de Arauco Argentina, Pablo Franzini, aport\u00f3 una visi\u00f3n estrat\u00e9gica basada en experiencia y escala: \u201cPara decidir d\u00f3nde invertir, necesitamos condiciones naturales, un marco macroecon\u00f3mico razonable y estabilidad. Con previsibilidad, el empresario asume riesgos; sin ella, la inversi\u00f3n migra.\u201d<\/p>\n\n\n\n<p>Franzini subray\u00f3 la urgencia de una reforma tributaria, adem\u00e1s de una reforma laboral, por la compleja superposici\u00f3n de impuestos nacionales, provinciales y municipales. Tambi\u00e9n puso el foco en modernizar la log\u00edstica \u2014incluyendo trenes\u2014 y destac\u00f3 la oportunidad hist\u00f3rica para avanzar hacia un tratado de libre comercio con Europa.<\/p>\n\n\n\n<p>Desde Corrientes, el ministro Claudio Anselmo reforz\u00f3 la visi\u00f3n proactiva: \u201cTenemos que salir a vendernos al mundo. Dar el primer paso\u201d, refiri\u00e9ndose a la exitosa visita oficial del Gobernador de Corrientes a la India. Anunci\u00f3 la creaci\u00f3n de la Agencia de Promoci\u00f3n de Inversiones de la provincia.<\/p>\n\n\n\n<p>Misiones aport\u00f3 un diagn\u00f3stico cr\u00edtico de la situaci\u00f3n PyME. El ministro Federico Fachinello se\u00f1al\u00f3 cierres, despidos y paralizaci\u00f3n de actividades, recordando que m\u00e1s del 75% de la producci\u00f3n va al mercado interno.<\/p>\n\n\n\n<p>Mercedes Ome\u00f1uka (FAIMA) pidi\u00f3 m\u00e1s y mejor acceso al cr\u00e9dito PyME, lo mismo que Osvaldo Kovalchuk (ASORA), quien llam\u00f3 a recuperar l\u00edneas del BNA y el BICE adaptadas al sector.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Acto de apertura<\/strong><\/h3>\n\n\n\n<p>El acto de apertura, que diera lugar al posterior brindis, estuvo a cargo de Marcos Pereda, vicepresidente de la entidad (SRA), seguido por Ignacio M\u00e9ndez Cunill director de la misma y productor forestal quien expres\u00f3:<\/p>\n\n\n\n<p>\u00a8Es un a\u00f1o complicado para todo el sector, bueno el mensaje es optimismo, las condiciones est\u00e1n dadas. Soy productor hace 20 a\u00f1os. Empec\u00e9 como productor forestal en Corrientes luego pusimos una industria, la empresa hoy en d\u00eda esta complicada, no es un momento f\u00e1cil, pero seguimos apostando. Seguimos plantando e invertimos en tecnificaci\u00f3n por que creemos en el sector\u00a8.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>En el mismo se entreg\u00f3 el premio CONFIAR 2025<\/strong><\/h3>\n\n\n\n<p>El Premio CONFIAR a la Innovaci\u00f3n y Desarrollo Sostenible distingui\u00f3 a ZENI, seleccionada entre ocho postulaciones de alt\u00edsimo nivel por su liderazgo integral en sostenibilidad, innovaci\u00f3n tecnol\u00f3gica y compromiso comunitario.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Patricio Zeni\" width=\"696\" height=\"522\" src=\"https:\/\/www.youtube.com\/embed\/GG8rGrnoqnI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Sostenibilidad ambiental<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Manejo      forestal certificado (FSC).<\/li>\n\n\n\n<li>L\u00edder      en manejo silvopastoril.<\/li>\n\n\n\n<li>Reducci\u00f3n      de emisiones, eficiencia h\u00eddrica y minimizaci\u00f3n de residuos.<\/li>\n\n\n\n<li>Uso      integral de biomasa residual para energ\u00eda (pellets).<\/li>\n<\/ul>\n\n\n\n<p>Innovaci\u00f3n<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Inversi\u00f3n      en I+D para diversificaci\u00f3n de productos de alto valor.<\/li>\n\n\n\n<li>Fuerte      presencia exportadora.<\/li>\n\n\n\n<li>Inserci\u00f3n      en mercados de carbono y servicios ecosist\u00e9micos.<\/li>\n<\/ul>\n\n\n\n<p>Impacto territorial<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Generaci\u00f3n      de empleo estable.<\/li>\n\n\n\n<li>Desarrollo      de proveedores y pymes asociadas.<\/li>\n\n\n\n<li>Transformaci\u00f3n      productiva de su regi\u00f3n forestal.<\/li>\n<\/ul>\n\n\n\n<p><a href=\"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/11\/21\/apicofom-baja-de-tasas-de-interes-y-reformas\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Leer: APICOFOM y expectativas por eventual baja de tasas de inter\u00e9s y reformas anunciadas (abre en una nueva pesta\u00f1a)\">Leer: APICOFOM y expectativas por eventual baja de tasas de inter\u00e9s y reformas anunciadas<\/a><\/p>\n\n\n\n<p>Fuente: <strong><a href=\"https:\/\/confiar.org.ar\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"CO (abre en una nueva pesta\u00f1a)\">CO<\/a><a href=\"https:\/\/confiar.org.ar\/\">NFIAR<\/a><\/strong> <\/p>\n\n\n\n<p>Foto y video: Enviado especial a La Rural.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jueves 4 de diciembre a las 19 horas, en el Auditorio de la Sociedad Rural Argentina se llev\u00f3 a cabo el brindis de fin de a\u00f1o organizado por CONFIAR (Consejo Foresto Industrial Argentino). A este le precedi\u00f3 la Mesa Foresto-Industrial en la cual participaron los principales referentes p\u00fablicos y privados del sector. Se sentaron [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":17881,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[],"class_list":{"0":"post-17880","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"category-featured"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONFIAR: Mesa Foresto-Industrial y brindis de fin de a\u00f1o<\/title>\n<meta name=\"description\" content=\"CONFIAR Mesa Foresto-Industrial: El objetivo de la misma era analizar lo alcanzado en el 2025 y las perspectivas del 2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONFIAR: Mesa Foresto-Industrial y brindis de fin de a\u00f1o\" \/>\n<meta property=\"og:description\" content=\"CONFIAR Mesa Foresto-Industrial: El objetivo de la misma era analizar lo alcanzado en el 2025 y las perspectivas del 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/\" \/>\n<meta property=\"og:site_name\" content=\"Desarrollo Forestal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Maderamen.Argentina\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-12T17:56:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T22:18:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2025\/12\/img_20251204_195250_517_hdr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1050\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maderamen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:site\" content=\"@DesarrolloFores\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maderamen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/\"},\"author\":{\"name\":\"Maderamen\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/person\\\/c05f216a5663a04adfc7d62d87295459\"},\"headline\":\"CONFIAR: Mesa Foresto-Industrial y brindis de fin de a\u00f1o\",\"datePublished\":\"2025-12-12T17:56:34+00:00\",\"dateModified\":\"2026-03-27T22:18:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/\"},\"wordCount\":672,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/img_20251204_195250_517_hdr.jpg\",\"articleSection\":[\"Noticias\",\"Principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/\",\"name\":\"CONFIAR: Mesa Foresto-Industrial y brindis de fin de a\u00f1o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/img_20251204_195250_517_hdr.jpg\",\"datePublished\":\"2025-12-12T17:56:34+00:00\",\"dateModified\":\"2026-03-27T22:18:49+00:00\",\"description\":\"CONFIAR Mesa Foresto-Industrial: El objetivo de la misma era analizar lo alcanzado en el 2025 y las perspectivas del 2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/img_20251204_195250_517_hdr.jpg\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/img_20251204_195250_517_hdr.jpg\",\"width\":1400,\"height\":1050,\"caption\":\"CONFIAR Mesa Foresto-Industrial\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/2025\\\/12\\\/12\\\/confiar-mesa-foresto-industria-y-brindis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONFIAR: Mesa Foresto-Industrial y brindis de fin de a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#website\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\",\"name\":\"Desarrollo Forestal\",\"description\":\"Noticias del sector forestal\",\"publisher\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#organization\",\"name\":\"Maderamen\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/maderamen-emago.png\",\"contentUrl\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/maderamen-emago.png\",\"width\":250,\"height\":246,\"caption\":\"Maderamen\"},\"image\":{\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Maderamen.Argentina\\\/\",\"https:\\\/\\\/x.com\\\/DesarrolloFores\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeYU2-_JRTYYpgHoyhTT2Fg\",\"https:\\\/\\\/www.instagram.com\\\/maderamen.ok\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maderameneditorial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/#\\\/schema\\\/person\\\/c05f216a5663a04adfc7d62d87295459\",\"name\":\"Maderamen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g\",\"caption\":\"Maderamen\"},\"url\":\"https:\\\/\\\/maderamen.com.ar\\\/desarrollo-forestal\\\/author\\\/maderamenadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONFIAR: Mesa Foresto-Industrial y brindis de fin de a\u00f1o","description":"CONFIAR Mesa Foresto-Industrial: El objetivo de la misma era analizar lo alcanzado en el 2025 y las perspectivas del 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/","og_locale":"es_ES","og_type":"article","og_title":"CONFIAR: Mesa Foresto-Industrial y brindis de fin de a\u00f1o","og_description":"CONFIAR Mesa Foresto-Industrial: El objetivo de la misma era analizar lo alcanzado en el 2025 y las perspectivas del 2026","og_url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/","og_site_name":"Desarrollo Forestal","article_publisher":"https:\/\/www.facebook.com\/Maderamen.Argentina\/","article_published_time":"2025-12-12T17:56:34+00:00","article_modified_time":"2026-03-27T22:18:49+00:00","og_image":[{"width":1400,"height":1050,"url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2025\/12\/img_20251204_195250_517_hdr.jpg","type":"image\/jpeg"}],"author":"Maderamen","twitter_card":"summary_large_image","twitter_creator":"@DesarrolloFores","twitter_site":"@DesarrolloFores","twitter_misc":{"Escrito por":"Maderamen","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/#article","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/"},"author":{"name":"Maderamen","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/person\/c05f216a5663a04adfc7d62d87295459"},"headline":"CONFIAR: Mesa Foresto-Industrial y brindis de fin de a\u00f1o","datePublished":"2025-12-12T17:56:34+00:00","dateModified":"2026-03-27T22:18:49+00:00","mainEntityOfPage":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/"},"wordCount":672,"commentCount":0,"publisher":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization"},"image":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/#primaryimage"},"thumbnailUrl":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2025\/12\/img_20251204_195250_517_hdr.jpg","articleSection":["Noticias","Principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/","name":"CONFIAR: Mesa Foresto-Industrial y brindis de fin de a\u00f1o","isPartOf":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/#primaryimage"},"image":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/#primaryimage"},"thumbnailUrl":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2025\/12\/img_20251204_195250_517_hdr.jpg","datePublished":"2025-12-12T17:56:34+00:00","dateModified":"2026-03-27T22:18:49+00:00","description":"CONFIAR Mesa Foresto-Industrial: El objetivo de la misma era analizar lo alcanzado en el 2025 y las perspectivas del 2026","breadcrumb":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/#primaryimage","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2025\/12\/img_20251204_195250_517_hdr.jpg","contentUrl":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2025\/12\/img_20251204_195250_517_hdr.jpg","width":1400,"height":1050,"caption":"CONFIAR Mesa Foresto-Industrial"},{"@type":"BreadcrumbList","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/2025\/12\/12\/confiar-mesa-foresto-industria-y-brindis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/"},{"@type":"ListItem","position":2,"name":"CONFIAR: Mesa Foresto-Industrial y brindis de fin de a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#website","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/","name":"Desarrollo Forestal","description":"Noticias del sector forestal","publisher":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#organization","name":"Maderamen","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/logo\/image\/","url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2026\/03\/maderamen-emago.png","contentUrl":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-content\/uploads\/sites\/2\/2026\/03\/maderamen-emago.png","width":250,"height":246,"caption":"Maderamen"},"image":{"@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Maderamen.Argentina\/","https:\/\/x.com\/DesarrolloFores","https:\/\/www.youtube.com\/channel\/UCeYU2-_JRTYYpgHoyhTT2Fg","https:\/\/www.instagram.com\/maderamen.ok\/","https:\/\/www.linkedin.com\/company\/maderameneditorial\/"]},{"@type":"Person","@id":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/#\/schema\/person\/c05f216a5663a04adfc7d62d87295459","name":"Maderamen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff28763266ad14d7e42092eb3998ef25a67b8fd98e7000d6029e8a2e785dc10?s=96&d=mm&r=g","caption":"Maderamen"},"url":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/author\/maderamenadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts\/17880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/comments?post=17880"}],"version-history":[{"count":1,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts\/17880\/revisions"}],"predecessor-version":[{"id":19083,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/posts\/17880\/revisions\/19083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/media\/17881"}],"wp:attachment":[{"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/media?parent=17880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/categories?post=17880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maderamen.com.ar\/desarrollo-forestal\/wp-json\/wp\/v2\/tags?post=17880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}